{"id":996402,"date":"2026-06-28T16:27:15","date_gmt":"2026-06-28T16:27:15","guid":{"rendered":"https:\/\/supeinnihonto.com\/product\/armadura-samurai-certificada-de-principios-del-periodo-edo-tokubetsu-kicho-shiryo\/"},"modified":"2026-08-31T16:51:44","modified_gmt":"2026-08-31T16:51:44","slug":"armadura-samurai-certificada-de-principios-del-periodo-edo-tokubetsu-kicho-shiryo","status":"publish","type":"product","link":"https:\/\/supeinnihonto.com\/es\/producto\/armadura-samurai-certificada-de-principios-del-periodo-edo-tokubetsu-kicho-shiryo\/","title":{"rendered":"Armadura samur\u00e1i certificada de principios del per\u00edodo Edo \u2014 Tokubetsu Kich\u014d Shiry\u014d"},"content":{"rendered":"<div class=\"product-scroll\">\n<h2>Armadura samur\u00e1i certificada de principios del per\u00edodo Edo (Gusoku) con kabuto \u014ckuwagata dorado<\/h2>\n<h3>Principios del per\u00edodo Edo, siglo XVII \u00b7 Tokubetsu Kich\u014d Shiry\u014d Certificado<\/h3>\n<p class=\"intro\">\n    Una espectacular y excepcionalmente rara armadura japonesa <em>gusoku<\/em> que data de principios del per\u00edodo Edo, se distingue por su magn\u00edfico par de imponentes menp\u014d dorados. <em>\u014dkuwagata<\/em> crestas y un impresionante lacado bermell\u00f3n <em><\/em>. Certificada oficialmente como <strong>Tokubetsu Kich\u014d Shiry\u014d<\/strong> por la <em>Nihon Katch\u016b Bugu Kenky\u016b Hozon Kai<\/em> (NKBKHK), esta armadura completa representa un ejemplo excepcional de la artesan\u00eda samur\u00e1i de principios del per\u00edodo Edo.<\/p>\n<p>\n    Las armaduras de este per\u00edodo son considerablemente m\u00e1s raras que los ejemplos de finales del per\u00edodo Edo que dominan el mercado actual. Su dataci\u00f3n de principios del siglo XVII, su excepcional estado de conservaci\u00f3n y su certificaci\u00f3n oficial japonesa sit\u00faan a este gusoku entre las categor\u00edas m\u00e1s codiciadas por los coleccionistas avanzados de armaduras japonesas.\n  <\/p>\n<hr>\n<h4>La coraza certificada <em>(D\u014d)<\/em><\/h4>\n<p>\n    La armadura se centra en una armadura de dos piezas finamente conservada, <em>nimai-d\u014d<\/em> construida con hierro lacado en negro mediante la t\u00e9cnica <em>kiritsuke-iyozane,<\/em>placas de hierro macizo cuidadosamente elaboradas para imitar escamas laminares individuales, ofreciendo una durabilidad superior.<\/p>\n<p>\n    La coraza est\u00e1 adornada con elegantes <em>sugake odoshi,<\/em> cordones de seda distintivos, <em>takuboku,<\/em> que combinan tonos crema, verde y azul. En la parte superior de la coraza, una banda de laca bermell\u00f3n granulada, de exquisita factura, contrasta armoniosamente con la laca negra intensa y el cord\u00f3n azul marino oscuro.<\/p>\n<p>\n    El resultado es una composici\u00f3n refinada a la vez que marcial, que demuestra la sofisticaci\u00f3n t\u00e9cnica alcanzada por los armeros japoneses a principios del per\u00edodo Edo.<\/p>\n<blockquote><p>\n    Esta armadura ha sido certificada oficialmente como <strong>Tokubetsu Kich\u014d Shiry\u014d<\/strong> por la Nihon Katch\u016b Bugu Kenky\u016b Hozon Kai (Certificado n.\u00ba 2361, 2025), una de las m\u00e1s altas distinciones otorgadas por la principal autoridad japonesa en armaduras tradicionales.<\/p>\n<\/blockquote>\n<hr>\n<h4>El Kabuto y el \u014ckuwagata<\/h4>\n<p>\n    El casco es imponente, lacado en negro. <em>con una cresta frontal dorada en forma de media luna, una m\u00e1scara facial lacada en negro con bigote de pelo natural, un protector de garganta lacado en rojo, hombreras de ocre dorado, protecci\u00f3n articulada para la falda, mangas de cota de malla y protectores de manos lacados en negro con un escudo familiar montado en metal.<\/p>\n<p>Lo m\u00e1s importante es que la armadura viene acompa\u00f1ada de un certificado de autenticidad emitido por la<\/em> con una copa puntiaguda y una cresta ondulada en relieve que decora la frente. Los <em>fukigaeshi<\/em> est\u00e1n cubiertos de cuero jaspeado finamente estampado y adornados con elegantes escudos familiares dorados (<em>mon<\/em>).\n  <\/p>\n<p>\n    Dominando la composici\u00f3n se encuentra un extraordinario par de monumentales escudos dorados <em>\u014dkuwagata<\/em>cuyas superficies patinadas por el fuego crean una de las siluetas m\u00e1s dram\u00e1ticas que se encuentran en las armaduras samur\u00e1i japonesas.\n  <\/p>\n<p>\n    Estos imponentes escudos en forma de asta simbolizaban la autoridad militar, el coraje y el prestigio, a la vez que hac\u00edan que quien los portaba fuera reconocible al instante en el campo de batalla.\n  <\/p>\n<hr>\n<h4>El Menp\u014d<\/h4>\n<p>\n    Debajo del casco se encuentra un llamativo escudo de hierro lacado en bermell\u00f3n <em><\/em>, acompa\u00f1ado de un A juego <em>yodarekake<\/em> Protector de garganta con cordones de seda tradicionales.<\/p>\n<p>\n    El v\u00edvido acabado bermell\u00f3n crea un contraste espectacular con la armadura negra, reforzando la apariencia fiera propia de la armadura de un samur\u00e1i de alto rango.<\/p>\n<p>\n    Tanto protectora como simb\u00f3lica, la m\u00e1scara proyecta fuerza y \u200b\u200bautoridad, a la vez que exhibe las refinadas t\u00e9cnicas de lacado de los artesanos de armaduras del per\u00edodo Edo.<\/p>\n<hr>\n<h4>Hombros, brazos y armadura inferior<\/h4>\n<p>\n    Grandes <em>Sode<\/em> Confeccionadas con finas l\u00e1minas color crema, protegen los hombros sobre un gorjal de capas <em>nodowa<\/em> .\n  <\/p>\n<p>\n    Los brazos Est\u00e1n protegidas por una armadura tradicional <em>kote<\/em> que combina cota de malla y placas de hierro sobre lujosa seda brocada, realzada con placas protectoras doradas.<\/p>\n<p>\n    La armadura inferior consta de <em><\/em>a juego, ricamente decoradas <em>haidate<\/em> cubierta de cuero estampado y lacada. <em>suneate<\/em> protegiendo las espinillas.<\/p>\n<p>\n    La seda verde celad\u00f3n combinada con un brocado floral ricamente tejido en oro y rojo proporciona un elegante contraste decorativo que realza el conjunto.<\/p>\n<hr>\n<h4>Color y car\u00e1cter est\u00e9tico<\/h4>\n<p>\n    La armadura exhibe una de las composiciones crom\u00e1ticas m\u00e1s impactantes que se encuentran en las armaduras japonesas.<\/p>\n<p>\n    La laca negra profunda constituye la base del conjunto, brillantemente contrastada por el imponente dorado <em>\u014dkuwagata<\/em> y el v\u00edvido bermell\u00f3n <em><\/em>. El cord\u00f3n de seda en tonos crema, verde y azul aporta mayor riqueza, manteniendo una perfecta armon\u00eda visual.<\/p>\n<p>\n    El resultado es una armadura que equilibra a la perfecci\u00f3n la autoridad en el campo de batalla con el refinado gusto art\u00edstico de la \u00e9lite samur\u00e1i del principio del per\u00edodo Edo.<\/p>\n<hr>\n<h4>Contexto hist\u00f3rico<\/h4>\n<p>\n    Esta armadura, que data de principios del per\u00edodo Edo, pertenece a una de las fases m\u00e1s codiciadas de la producci\u00f3n de armaduras japonesas. A diferencia de los ejemplos mucho m\u00e1s comunes del final del per\u00edodo Edo que se encuentran en el mercado actual, las armaduras del siglo XVII se conservan en cantidades considerablemente menores y ofrecen a los coleccionistas una conexi\u00f3n mucho m\u00e1s cercana con las grandes tradiciones militares que siguieron inmediatamente a la unificaci\u00f3n de Jap\u00f3n bajo el shogunato Tokugawa.<\/p>\n<p>\n    Aunque la guerra a gran escala hab\u00eda comenzado a declinar, los samur\u00e1is continuaron encargando magn\u00edficas armaduras que reflejaban tanto su herencia militar como su estatus social. Los fabricantes de armaduras combinaron la construcci\u00f3n pr\u00e1ctica desarrollada durante el per\u00edodo Sengoku con t\u00e9cnicas decorativas cada vez m\u00e1s refinadas, creando obras que equilibraban la funcionalidad en el campo de batalla con una excepcional sofisticaci\u00f3n art\u00edstica.<\/p>\n<hr>\n<h4>Certificaci\u00f3n Tokubetsu Kich\u014d Shiry\u014d<\/h4>\n<p>\n    Esta armadura viene acompa\u00f1ada de un <strong>Tokubetsu Kich\u014d Shiry\u014d<\/strong> certificado emitido por la <em>Nihon Katch\u016b Bugu Kenky\u016b Hozon Kai<\/em> (NKBKHK), certificado n\u00famero <strong>2361<\/strong>emitido en 2025.\n  <\/p>\n<p>\n    La certificaci\u00f3n Tokubetsu Kich\u014d Shiry\u014d representa uno de los niveles m\u00e1s altos de certificaci\u00f3n otorgados por la principal autoridad japonesa dedicada al estudio y la preservaci\u00f3n de las armaduras tradicionales japonesas. Esta designaci\u00f3n est\u00e1 reservada para piezas de especial importancia hist\u00f3rica y art\u00edstica que tambi\u00e9n han sido seleccionadas como candidatas al siguiente nivel de certificaci\u00f3n de la organizaci\u00f3n.<\/p>\n<p>\n    A modo de comparaci\u00f3n, este nivel se considera generalmente equivalente a la <strong>Tokubetsu Hozon<\/strong> certificaci\u00f3n emitida por la NBTHK para espadas japonesas, que confirma que la armadura posee una calidad muy superior al nivel de certificaci\u00f3n est\u00e1ndar.<\/p>\n<hr>\n<h4>Especificaciones<\/h4>\n<ul>\n<li><strong>Clasificaci\u00f3n:<\/strong> Gusoku japon\u00e9s completo (\u5177\u8db3)<\/li>\n<li><strong>\u00c9poca:<\/strong> Principios del per\u00edodo Edo (siglo XVII)<\/li>\n<li><strong>Tipo:<\/strong> Nimai-d\u014d Gusoku de hierro lacado en negro, estilo Kiritsuke-Iyozane, con sugake odoshi<\/li>\n<li><strong>Coraza:<\/strong> Nimai-d\u014d de hierro lacado en negro de dos piezas, estilo Kiritsuke-Iyozane<\/li>\n<li><strong>Cord\u00f3n:<\/strong> Sugake odoshi con cordones de seda Takuboku<\/li>\n<li><strong>Kabuto:<\/strong> Casco lacado en negro con escudos \u014ckuwagata dorados<\/li>\n<li><strong>Fukigaeshi:<\/strong> Cuero estampado con escudos familiares dorados (Lun)<\/li>\n<li><strong>M\u00e1scara facial:<\/strong> Menp\u014d de hierro lacado en bermell\u00f3n con Yodarekake<\/li>\n<li><strong>Hombreras:<\/strong> Sode grande con ribete color crema<\/li>\n<li><strong>Protecci\u00f3n de brazos:<\/strong> Kote con cota de malla, placas de hierro y refuerzos dorados<\/li>\n<li><strong>Armadura inferior:<\/strong> Kusazuri, Haidate recubierto de cuero y Suneate lacado<\/li>\n<li><strong>Certificaci\u00f3n:<\/strong> Tokubetsu Kich\u014d Shiry\u014d \u2014 NKBKHK n.\u00b0 2361 (2025)<\/li>\n<\/ul>\n<hr>\n<h4>Valor de coleccionista<\/h4>\n<p>\n    Las armaduras del per\u00edodo Edo temprano, certificadas al nivel Tokubetsu Kich\u014d Shiry\u014d, son muy dif\u00edciles de encontrar en el mercado internacional. La combinaci\u00f3n de una dataci\u00f3n autentificada del siglo XVII, un magn\u00edfico dorado <em>\u014dkuwagata<\/em>, un llamativo color bermell\u00f3n <em><\/em>, una configuraci\u00f3n completa lista para exhibici\u00f3n y una de las certificaciones m\u00e1s altas disponibles para armaduras japonesas, la convierten en una pieza de colecci\u00f3n excepcional.<\/p>\n<p>\n    Cabe destacar su \u00e9poca. Si bien la mayor\u00eda de las armaduras japonesas que se conservan hoy en d\u00eda datan del final del per\u00edodo Edo, los ejemplares autentificados del principio del per\u00edodo Edo son significativamente m\u00e1s escasos y, por lo tanto, se consideran mucho m\u00e1s valiosos entre los coleccionistas avanzados.\n  <\/p>\n<p class=\"closing\">\n    Combinando una notable importancia hist\u00f3rica, certificaci\u00f3n oficial japonesa, una artesan\u00eda excepcional y una de las presentaciones visuales m\u00e1s impactantes que se pueden encontrar en armaduras samur\u00e1i, esta magn\u00edfica pieza del per\u00edodo Edo temprano es una joya. <em>gusoku<\/em> Representa una oportunidad excepcional para adquirir una aut\u00e9ntica obra maestra de la tradici\u00f3n guerrera japonesa y una de las expresiones m\u00e1s refinadas del arte militar japon\u00e9s.\n  <\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Armadura samur\u00e1i certificada de principios del per\u00edodo Edo (Gusoku) con kabuto \u014ckuwagata dorado Principios del per\u00edodo Edo, siglo XVII \u00b7 Tokubetsu Kich\u014d Shiry\u014d Certificado Una espectacular y excepcionalmente rara armadura japonesa gusoku que data de principios del per\u00edodo Edo, se distingue por su magn\u00edfico par de imponentes menp\u014d dorados. \u014dkuwagata crestas y un impresionante lacado bermell\u00f3n . Certificada oficialmente como Tokubetsu Kich\u014d Shiry\u014d por la Nihon Katch\u016b Bugu Kenky\u016b Hozon Kai (NKBKHK), esta armadura completa representa un ejemplo excepcional de la artesan\u00eda samur\u00e1i de principios del per\u00edodo Edo. Las armaduras de este per\u00edodo son considerablemente m\u00e1s raras que los ejemplos de finales del per\u00edodo Edo que dominan el mercado actual. Su dataci\u00f3n de principios del siglo XVII, su excepcional estado de conservaci\u00f3n y su certificaci\u00f3n oficial japonesa sit\u00faan a este gusoku entre las categor\u00edas m\u00e1s codiciadas por los coleccionistas avanzados de armaduras japonesas. La coraza certificada (D\u014d) La armadura se centra en una armadura de dos piezas finamente conservada, nimai-d\u014d construida con hierro lacado en negro mediante la t\u00e9cnica kiritsuke-iyozane,placas de hierro macizo cuidadosamente elaboradas para imitar escamas laminares individuales, ofreciendo una durabilidad superior. La coraza est\u00e1 adornada con elegantes sugake odoshi, cordones de seda distintivos, takuboku, que combinan tonos crema, verde y azul. En la parte superior de la coraza, una banda de laca bermell\u00f3n granulada, de exquisita factura, contrasta armoniosamente con la laca negra intensa y el cord\u00f3n azul marino oscuro. El resultado es una composici\u00f3n refinada a la vez que marcial, que demuestra la sofisticaci\u00f3n t\u00e9cnica alcanzada por los armeros japoneses a principios del per\u00edodo Edo. Esta armadura ha sido certificada oficialmente como Tokubetsu Kich\u014d Shiry\u014d por la Nihon Katch\u016b Bugu Kenky\u016b Hozon Kai (Certificado n.\u00ba 2361, 2025), una de las m\u00e1s altas distinciones otorgadas por la principal autoridad japonesa en armaduras tradicionales. El Kabuto y el \u014ckuwagata El casco es imponente, lacado en negro. con una cresta frontal dorada en forma de media luna, una m\u00e1scara facial lacada en negro con bigote de pelo natural, un protector de garganta lacado en rojo, hombreras de ocre dorado, protecci\u00f3n articulada para la falda, mangas de cota de malla y protectores de manos lacados en negro con un escudo familiar montado en metal. Lo m\u00e1s importante es que la armadura viene acompa\u00f1ada de un certificado de autenticidad emitido por la con una copa puntiaguda y una cresta ondulada en relieve que decora la frente. Los fukigaeshi est\u00e1n cubiertos de cuero jaspeado finamente estampado y adornados con elegantes escudos familiares dorados (mon). Dominando la composici\u00f3n se encuentra un extraordinario par de monumentales escudos dorados \u014dkuwagatacuyas superficies patinadas por el fuego crean una de las siluetas m\u00e1s dram\u00e1ticas que se encuentran en las armaduras samur\u00e1i japonesas. Estos imponentes escudos en forma de asta simbolizaban la autoridad militar, el coraje y el prestigio, a la vez que hac\u00edan que quien los portaba fuera reconocible al instante en el campo de batalla. El Menp\u014d Debajo del casco se encuentra un llamativo escudo de hierro lacado en bermell\u00f3n , acompa\u00f1ado de un A juego yodarekake Protector de garganta con cordones de seda tradicionales. El v\u00edvido acabado bermell\u00f3n crea un contraste espectacular con la armadura negra, reforzando la apariencia fiera propia de la armadura de un samur\u00e1i de alto rango. Tanto protectora como simb\u00f3lica, la m\u00e1scara proyecta fuerza y \u200b\u200bautoridad, a la vez que exhibe las refinadas t\u00e9cnicas de lacado de los artesanos de armaduras del per\u00edodo Edo. Hombros, brazos y armadura inferior Grandes Sode Confeccionadas con finas l\u00e1minas color crema, protegen los hombros sobre un gorjal de capas nodowa . Los brazos Est\u00e1n protegidas por una armadura tradicional kote que combina cota de malla y placas de hierro sobre lujosa seda brocada, realzada con placas protectoras doradas. La armadura inferior consta de a juego, ricamente decoradas haidate cubierta de cuero estampado y lacada. suneate protegiendo las espinillas. La seda verde celad\u00f3n combinada con un brocado floral ricamente tejido en oro y rojo proporciona un elegante contraste decorativo que realza el conjunto. Color y car\u00e1cter est\u00e9tico La armadura exhibe una de las composiciones crom\u00e1ticas m\u00e1s impactantes que se encuentran en las armaduras japonesas. La laca negra profunda constituye la base del conjunto, brillantemente contrastada por el imponente dorado \u014dkuwagata y el v\u00edvido bermell\u00f3n . El cord\u00f3n de seda en tonos crema, verde y azul aporta mayor riqueza, manteniendo una perfecta armon\u00eda visual. El resultado es una armadura que equilibra a la perfecci\u00f3n la autoridad en el campo de batalla con el refinado gusto art\u00edstico de la \u00e9lite samur\u00e1i del principio del per\u00edodo Edo. Contexto hist\u00f3rico Esta armadura, que data de principios del per\u00edodo Edo, pertenece a una de las fases m\u00e1s codiciadas de la producci\u00f3n de armaduras japonesas. A diferencia de los ejemplos mucho m\u00e1s comunes del final del per\u00edodo Edo que se encuentran en el mercado actual, las armaduras del siglo XVII se conservan en cantidades considerablemente menores y ofrecen a los coleccionistas una conexi\u00f3n mucho m\u00e1s cercana con las grandes tradiciones militares que siguieron inmediatamente a la unificaci\u00f3n de Jap\u00f3n bajo el shogunato Tokugawa. Aunque la guerra a gran escala hab\u00eda comenzado a declinar, los samur\u00e1is continuaron encargando magn\u00edficas armaduras que reflejaban tanto su herencia militar como su estatus social. Los fabricantes de armaduras combinaron la construcci\u00f3n pr\u00e1ctica desarrollada durante el per\u00edodo Sengoku con t\u00e9cnicas decorativas cada vez m\u00e1s refinadas, creando obras que equilibraban la funcionalidad en el campo de batalla con una excepcional sofisticaci\u00f3n art\u00edstica. Certificaci\u00f3n Tokubetsu Kich\u014d Shiry\u014d Esta armadura viene acompa\u00f1ada de un Tokubetsu Kich\u014d Shiry\u014d certificado emitido por la Nihon Katch\u016b Bugu Kenky\u016b Hozon Kai (NKBKHK), certificado n\u00famero 2361emitido en 2025. La certificaci\u00f3n Tokubetsu Kich\u014d Shiry\u014d representa uno de los niveles m\u00e1s altos de certificaci\u00f3n otorgados por la principal autoridad japonesa dedicada al estudio y la preservaci\u00f3n de las armaduras tradicionales japonesas. Esta designaci\u00f3n est\u00e1 reservada para piezas de especial importancia hist\u00f3rica y art\u00edstica que tambi\u00e9n han sido seleccionadas como candidatas al siguiente nivel de certificaci\u00f3n de la organizaci\u00f3n. A modo de comparaci\u00f3n, este nivel se considera generalmente equivalente a la Tokubetsu Hozon certificaci\u00f3n emitida por la NBTHK<\/p>\n","protected":false},"featured_media":996437,"template":"","meta":[],"product_brand":[],"product_cat":[1073,1074],"product_tag":[1094,1096],"class_list":["post-996402","product","type-product","status-publish","has-post-thumbnail","product_cat-armaduras","product_cat-gusoku-yoroi","product_tag-edo","product_tag-gusoku","first","instock","featured","sold-individually","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Armadura samur\u00e1i certificada de principios del per\u00edodo Edo \u2014 Tokubetsu Kich\u014d Shiry\u014d - Supein Nihonto<\/title>\n<meta name=\"description\" content=\"Aut\u00e9ntica armadura samur\u00e1i del Edo temprano (gusoku) certificada por Tokubetsu Kich\u014d Shiry\u014d, con un borde dorado. Kabuto \u014ckuwagata, menp\u014d bermell\u00f3n y armadura japonesa completa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/supeinnihonto.com\/product\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Armadura samur\u00e1i certificada de principios del per\u00edodo Edo \u2014 Tokubetsu Kich\u014d Shiry\u014d - Supein Nihonto\" \/>\n<meta property=\"og:description\" content=\"Aut\u00e9ntica armadura samur\u00e1i del Edo temprano (gusoku) certificada por Tokubetsu Kich\u014d Shiry\u014d, con un borde dorado. Kabuto \u014ckuwagata, menp\u014d bermell\u00f3n y armadura japonesa completa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/supeinnihonto.com\/product\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\/\" \/>\n<meta property=\"og:site_name\" content=\"Supein Nihonto\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T16:51:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/06\/Certified-Early-Edo-Samurai-Armor-Tokubetsu-Kicho-Shiryo-34.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1232\" \/>\n\t<meta property=\"og:image:height\" content=\"820\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\\\/\",\"name\":\"Armadura samur\u00e1i certificada de principios del per\u00edodo Edo \u2014 Tokubetsu Kich\u014d Shiry\u014d - Supein Nihonto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Certified-Early-Edo-Samurai-Armor-Tokubetsu-Kicho-Shiryo-34.jpg\",\"datePublished\":\"2026-06-28T16:27:15+00:00\",\"dateModified\":\"2026-08-31T16:51:44+00:00\",\"description\":\"Aut\u00e9ntica armadura samur\u00e1i del Edo temprano (gusoku) certificada por Tokubetsu Kich\u014d Shiry\u014d, con un borde dorado. Kabuto \u014ckuwagata, menp\u014d bermell\u00f3n y armadura japonesa completa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Certified-Early-Edo-Samurai-Armor-Tokubetsu-Kicho-Shiryo-34.jpg\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Certified-Early-Edo-Samurai-Armor-Tokubetsu-Kicho-Shiryo-34.jpg\",\"width\":1232,\"height\":820,\"caption\":\"Armadura samur\u00e1i certificada de principios del per\u00edodo Edo \u2014 Tokubetsu Kich\u014d Shiry\u014d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Armadura samur\u00e1i certificada de principios del per\u00edodo Edo \u2014 Tokubetsu Kich\u014d Shiry\u014d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"name\":\"Supein Nihonto\",\"description\":\"Authentic japanese Nihonto katana\",\"publisher\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/supeinnihonto.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\",\"name\":\"SupeinNihonto\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"width\":400,\"height\":400,\"caption\":\"SupeinNihonto\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Armadura samur\u00e1i certificada de principios del per\u00edodo Edo \u2014 Tokubetsu Kich\u014d Shiry\u014d - Supein Nihonto","description":"Aut\u00e9ntica armadura samur\u00e1i del Edo temprano (gusoku) certificada por Tokubetsu Kich\u014d Shiry\u014d, con un borde dorado. Kabuto \u014ckuwagata, menp\u014d bermell\u00f3n y armadura japonesa completa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/supeinnihonto.com\/product\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\/","og_locale":"es_ES","og_type":"article","og_title":"Armadura samur\u00e1i certificada de principios del per\u00edodo Edo \u2014 Tokubetsu Kich\u014d Shiry\u014d - Supein Nihonto","og_description":"Aut\u00e9ntica armadura samur\u00e1i del Edo temprano (gusoku) certificada por Tokubetsu Kich\u014d Shiry\u014d, con un borde dorado. Kabuto \u014ckuwagata, menp\u014d bermell\u00f3n y armadura japonesa completa.","og_url":"https:\/\/supeinnihonto.com\/product\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\/","og_site_name":"Supein Nihonto","article_modified_time":"2026-08-31T16:51:44+00:00","og_image":[{"width":1232,"height":820,"url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/06\/Certified-Early-Edo-Samurai-Armor-Tokubetsu-Kicho-Shiryo-34.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/supeinnihonto.com\/product\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\/","url":"https:\/\/supeinnihonto.com\/product\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\/","name":"Armadura samur\u00e1i certificada de principios del per\u00edodo Edo \u2014 Tokubetsu Kich\u014d Shiry\u014d - Supein Nihonto","isPartOf":{"@id":"https:\/\/supeinnihonto.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/supeinnihonto.com\/product\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\/#primaryimage"},"image":{"@id":"https:\/\/supeinnihonto.com\/product\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\/#primaryimage"},"thumbnailUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/06\/Certified-Early-Edo-Samurai-Armor-Tokubetsu-Kicho-Shiryo-34.jpg","datePublished":"2026-06-28T16:27:15+00:00","dateModified":"2026-08-31T16:51:44+00:00","description":"Aut\u00e9ntica armadura samur\u00e1i del Edo temprano (gusoku) certificada por Tokubetsu Kich\u014d Shiry\u014d, con un borde dorado. Kabuto \u014ckuwagata, menp\u014d bermell\u00f3n y armadura japonesa completa.","breadcrumb":{"@id":"https:\/\/supeinnihonto.com\/product\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/supeinnihonto.com\/product\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/product\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\/#primaryimage","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/06\/Certified-Early-Edo-Samurai-Armor-Tokubetsu-Kicho-Shiryo-34.jpg","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/06\/Certified-Early-Edo-Samurai-Armor-Tokubetsu-Kicho-Shiryo-34.jpg","width":1232,"height":820,"caption":"Armadura samur\u00e1i certificada de principios del per\u00edodo Edo \u2014 Tokubetsu Kich\u014d Shiry\u014d"},{"@type":"BreadcrumbList","@id":"https:\/\/supeinnihonto.com\/product\/certified-early-edo-samurai-armor-tokubetsu-kicho-shiryo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/supeinnihonto.com\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/supeinnihonto.com\/tienda\/"},{"@type":"ListItem","position":3,"name":"Armadura samur\u00e1i certificada de principios del per\u00edodo Edo \u2014 Tokubetsu Kich\u014d Shiry\u014d"}]},{"@type":"WebSite","@id":"https:\/\/supeinnihonto.com\/#website","url":"https:\/\/supeinnihonto.com\/","name":"Supein Nihonto","description":"Authentic japanese Nihonto katana","publisher":{"@id":"https:\/\/supeinnihonto.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/supeinnihonto.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/supeinnihonto.com\/#organization","name":"SupeinNihonto","url":"https:\/\/supeinnihonto.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","width":400,"height":400,"caption":"SupeinNihonto"},"image":{"@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/996402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/996402\/revisions"}],"predecessor-version":[{"id":997536,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/996402\/revisions\/997536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media\/996437"}],"wp:attachment":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media?parent=996402"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_brand?post=996402"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_cat?post=996402"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_tag?post=996402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}