{"id":995349,"date":"2026-05-23T08:07:15","date_gmt":"2026-05-23T08:07:15","guid":{"rendered":"https:\/\/supeinnihonto.com\/product\/mascara-noh-yaseonna\/"},"modified":"2026-05-23T08:07:15","modified_gmt":"2026-05-23T08:07:15","slug":"mascara-noh-yaseonna","status":"publish","type":"product","link":"https:\/\/supeinnihonto.com\/es\/producto\/mascara-noh-yaseonna\/","title":{"rendered":"M\u00e1scara Noh Yaseonna"},"content":{"rendered":"<p><span>M\u00e1scara de madera tallada del teatro Noh, periodo Showa. Firmado por Seiun \u9759\u96f2. Representa el esp\u00edritu sufriente de una mujer que muere por problemas en una relaci\u00f3n amorosa.<br \/>\n<\/span><\/p>\n<p><span>N<\/span><span>Las m\u00e1scaras Noh han sido durante mucho tiempo una parte integral de los rituales religiosos, festivales y teatro de Jap\u00f3n. Representan figuras hist\u00f3ricas y esp\u00edritus conocidos como\u00a0<\/span><i>kami<\/i><span>, que tienen su origen en las creencias ind\u00edgenas de Jap\u00f3n. Tradicionalmente, la m\u00e1scara simbolizaba la \u00abposesi\u00f3n\u00bb, transformando a quien la llevaba en el\u00a0<\/span><i>kami<\/i><span>\u00a0o su encarnaci\u00f3n humana.<br \/>\n<\/span><\/p>\n<p>Escala 1:1 (20 x 15 cm aprox.)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1scara de madera tallada del teatro Noh, periodo Showa. Firmado por Seiun \u9759\u96f2. Representa el esp\u00edritu sufriente de una mujer que muere por problemas en una relaci\u00f3n amorosa. NLas m\u00e1scaras Noh han sido durante mucho tiempo una parte integral de los rituales religiosos, festivales y teatro de Jap\u00f3n. Representan figuras hist\u00f3ricas y esp\u00edritus conocidos como\u00a0kami, que tienen su origen en las creencias ind\u00edgenas de Jap\u00f3n. Tradicionalmente, la m\u00e1scara simbolizaba la \u00abposesi\u00f3n\u00bb, transformando a quien la llevaba en el\u00a0kami\u00a0o su encarnaci\u00f3n humana. Escala 1:1 (20 x 15 cm aprox.) &nbsp;<\/p>\n","protected":false},"featured_media":995350,"template":"","meta":[],"product_brand":[],"product_cat":[1082],"product_tag":[1136],"class_list":["post-995349","product","type-product","status-publish","has-post-thumbnail","product_cat-noh-masks","product_tag-mascara-no-de-madera","first","outofstock","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1scara Noh Yaseonna - Supein Nihonto<\/title>\n<meta name=\"description\" content=\"M\u00e1scara de madera tallada del teatro Noh, periodo Showa. Firmado por Seiun \u9759\u96f2. Representa el esp\u00edritu sufriente de una mujer que muere por problemas en una relaci\u00f3n amorosa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/supeinnihonto.com\/product\/noh-mask-yaseonna\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1scara Noh Yaseonna - Supein Nihonto\" \/>\n<meta property=\"og:description\" content=\"M\u00e1scara de madera tallada del teatro Noh, periodo Showa. Firmado por Seiun \u9759\u96f2. Representa el esp\u00edritu sufriente de una mujer que muere por problemas en una relaci\u00f3n amorosa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/supeinnihonto.com\/product\/noh-mask-yaseonna\/\" \/>\n<meta property=\"og:site_name\" content=\"Supein Nihonto\" \/>\n<meta property=\"og:image\" content=\"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/GEO9306.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1889\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/noh-mask-yaseonna\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/noh-mask-yaseonna\\\/\",\"name\":\"M\u00e1scara Noh Yaseonna - Supein Nihonto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/noh-mask-yaseonna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/noh-mask-yaseonna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GEO9306.webp\",\"datePublished\":\"2026-05-23T08:07:15+00:00\",\"description\":\"M\u00e1scara de madera tallada del teatro Noh, periodo Showa. Firmado por Seiun \u9759\u96f2. Representa el esp\u00edritu sufriente de una mujer que muere por problemas en una relaci\u00f3n amorosa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/noh-mask-yaseonna\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/noh-mask-yaseonna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/noh-mask-yaseonna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GEO9306.webp\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GEO9306.webp\",\"width\":2048,\"height\":1889,\"caption\":\"Noh mask Yaseonna\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/noh-mask-yaseonna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00e1scara Noh Yaseonna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"name\":\"Supein Nihonto\",\"description\":\"Authentic japanese Nihonto katana\",\"publisher\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/supeinnihonto.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\",\"name\":\"SupeinNihonto\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"width\":400,\"height\":400,\"caption\":\"SupeinNihonto\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1scara Noh Yaseonna - Supein Nihonto","description":"M\u00e1scara de madera tallada del teatro Noh, periodo Showa. Firmado por Seiun \u9759\u96f2. Representa el esp\u00edritu sufriente de una mujer que muere por problemas en una relaci\u00f3n amorosa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/supeinnihonto.com\/product\/noh-mask-yaseonna\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1scara Noh Yaseonna - Supein Nihonto","og_description":"M\u00e1scara de madera tallada del teatro Noh, periodo Showa. Firmado por Seiun \u9759\u96f2. Representa el esp\u00edritu sufriente de una mujer que muere por problemas en una relaci\u00f3n amorosa.","og_url":"https:\/\/supeinnihonto.com\/product\/noh-mask-yaseonna\/","og_site_name":"Supein Nihonto","og_image":[{"width":2048,"height":1889,"url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/GEO9306.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/supeinnihonto.com\/product\/noh-mask-yaseonna\/","url":"https:\/\/supeinnihonto.com\/product\/noh-mask-yaseonna\/","name":"M\u00e1scara Noh Yaseonna - Supein Nihonto","isPartOf":{"@id":"https:\/\/supeinnihonto.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/supeinnihonto.com\/product\/noh-mask-yaseonna\/#primaryimage"},"image":{"@id":"https:\/\/supeinnihonto.com\/product\/noh-mask-yaseonna\/#primaryimage"},"thumbnailUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/GEO9306.webp","datePublished":"2026-05-23T08:07:15+00:00","description":"M\u00e1scara de madera tallada del teatro Noh, periodo Showa. Firmado por Seiun \u9759\u96f2. Representa el esp\u00edritu sufriente de una mujer que muere por problemas en una relaci\u00f3n amorosa.","breadcrumb":{"@id":"https:\/\/supeinnihonto.com\/product\/noh-mask-yaseonna\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/supeinnihonto.com\/product\/noh-mask-yaseonna\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/product\/noh-mask-yaseonna\/#primaryimage","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/GEO9306.webp","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/GEO9306.webp","width":2048,"height":1889,"caption":"Noh mask Yaseonna"},{"@type":"BreadcrumbList","@id":"https:\/\/supeinnihonto.com\/product\/noh-mask-yaseonna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/supeinnihonto.com\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/supeinnihonto.com\/tienda\/"},{"@type":"ListItem","position":3,"name":"M\u00e1scara Noh Yaseonna"}]},{"@type":"WebSite","@id":"https:\/\/supeinnihonto.com\/#website","url":"https:\/\/supeinnihonto.com\/","name":"Supein Nihonto","description":"Authentic japanese Nihonto katana","publisher":{"@id":"https:\/\/supeinnihonto.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/supeinnihonto.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/supeinnihonto.com\/#organization","name":"SupeinNihonto","url":"https:\/\/supeinnihonto.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","width":400,"height":400,"caption":"SupeinNihonto"},"image":{"@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/995349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/995349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media\/995350"}],"wp:attachment":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media?parent=995349"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_brand?post=995349"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_cat?post=995349"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_tag?post=995349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}