{"id":995009,"date":"2026-05-23T08:19:56","date_gmt":"2026-05-23T08:19:56","guid":{"rendered":"https:\/\/supeinnihonto.com\/product\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/"},"modified":"2026-05-23T08:19:56","modified_gmt":"2026-05-23T08:19:56","slug":"wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial","status":"publish","type":"product","link":"https:\/\/supeinnihonto.com\/es\/producto\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/","title":{"rendered":"Wakizashi nihont\u014d con koshirae de la Segunda Guerra Mundial"},"content":{"rendered":"<p><strong>DESCRIPCI\u00d3N DEL ART\u00cdCULO:<\/strong><\/p>\n<p>Incluye kimono o bolsa de algod\u00f3n. Incluye certificado de autenticidad de Nihonto. Incluye copia del Tokosusho.<\/p>\n<h3 data-start=\"2094\" data-end=\"2115\"><strong data-start=\"2098\" data-end=\"2115\">Documentaci\u00f3n<\/strong><\/h3>\n<div class=\"TyagGW_tableContainer\">\n<p data-start=\"5105\" data-end=\"5165\"><strong data-start=\"5105\" data-end=\"5117\">\u9283\u7832\u5200\u5263\u985e\u767b\u9332\u8a3c<\/strong><br data-start=\"5117\" data-end=\"5120\" \/>Certificado de registro de armas de fuego y espadas\n<\/p>\n<p data-start=\"5239\" data-end=\"5304\"><strong data-start=\"5239\" data-end=\"5256\">\u5200\u5263\u985e \/ \u5200\u5263 \/ \u7a2e\u5225<\/strong>: <strong data-start=\"5258\" data-end=\"5266\">\u308f\u304d\u3056\u3057<\/strong><br data-start=\"5266\" data-end=\"5269\" \/>Clasificaci\u00f3n de espada: <strong data-start=\"5291\" data-end=\"5304\">Wakizashi<\/strong><\/p>\n<p data-start=\"5306\" data-end=\"5357\"><strong data-start=\"5306\" data-end=\"5312\">\u9577\u3055<\/strong>: <strong data-start=\"5314\" data-end=\"5329\">\u4e94\u4e09\u30fb\u56db\u30bb\u30f3\u30c1\u30e1\u30fc\u30c8\u30eb<\/strong><br data-start=\"5329\" data-end=\"5332\" \/>Longitud de la hoja: <strong data-start=\"5346\" data-end=\"5357\">53,4 cm<\/strong><\/p>\n<p data-start=\"5359\" data-end=\"5412\"><strong data-start=\"5359\" data-end=\"5365\">\u53cd\u308a<\/strong>: <strong data-start=\"5367\" data-end=\"5381\">\u4e8c\u30fb\u3007\u30bb\u30f3\u30c1\u30e1\u30fc\u30c8\u30eb<\/strong><br data-start=\"5381\" data-end=\"5384\" \/>Curvatura (sori): <strong data-start=\"5402\" data-end=\"5412\">2,0 cm<\/strong><\/p>\n<p data-start=\"5414\" data-end=\"5541\"><strong data-start=\"5414\" data-end=\"5422\">\u76ee\u304f\u304e\u7a74<\/strong>: (la anotaci\u00f3n manuscrita es irregular en el documento)<br data-start=\"5472\" data-end=\"5475\" \/>La hoja muestra claramente: <strong data-start=\"5506\" data-end=\"5524\">dos mekugi-ana<\/strong> (dos orificios para clavijas).\n<\/p>\n<p data-start=\"5543\" data-end=\"5605\"><strong data-start=\"5543\" data-end=\"5549\">\u9298\u6587<\/strong>: <strong data-start=\"5551\" data-end=\"5557\">\u7121\u9298<\/strong><br data-start=\"5557\" data-end=\"5560\" \/>Firma\/inscripci\u00f3n: <strong data-start=\"5585\" data-end=\"5605\">Mumei (sin firmar)<\/strong><\/p>\n<p data-start=\"5666\" data-end=\"5740\"><strong data-start=\"5666\" data-end=\"5678\">\u611b\u5a9b\u770c\u6559\u80b2\u59d4\u54e1\u4f1a<\/strong><br data-start=\"5678\" data-end=\"5681\" \/>Autoridad emisora: <strong data-start=\"5700\" data-end=\"5740\">\u00a0Junta de Educaci\u00f3n Prefectural<\/strong><\/p>\n<p data-start=\"5742\" data-end=\"5849\">\n<hr data-start=\"5851\" data-end=\"5854\" \/>\n<h3 data-start=\"5856\" data-end=\"5895\">Smith \/ escuela \/ per\u00edodo y contexto<\/h3>\n<p data-start=\"5897\" data-end=\"6153\"><strong data-start=\"5897\" data-end=\"5918\">Mumei (sin firmar)<\/strong><br data-start=\"5918\" data-end=\"5921\" \/>Esta es una <strong data-start=\"5932\" data-end=\"5954\">antigua hoja japonesa<\/strong>, con una cronolog\u00eda de mercado y caracter\u00edsticas tipol\u00f3gicas consistentes con el <strong data-start=\"6024\" data-end=\"6061\">finales del per\u00edodo Muromachi \/ principios del per\u00edodo Edo<\/strong>, posteriormente <strong data-start=\"6069\" data-end=\"6152\">remontada en un koshirae militar japon\u00e9s de la era Sh\u014dwa (Segunda Guerra Mundial)<\/strong>.<\/p>\n<p data-start=\"6155\" data-end=\"6258\">Este tipo de ensamblaje es especialmente atractivo porque combina dos campos de coleccionismo en un solo objeto:<\/p>\n<ul data-start=\"6260\" data-end=\"6332\">\n<li data-start=\"6260\" data-end=\"6292\">\n<p data-start=\"6262\" data-end=\"6292\">una <strong data-start=\"6265\" data-end=\"6292\">antigua tradicional nihont\u014d<\/strong><\/p>\n<\/li>\n<li data-start=\"6293\" data-end=\"6332\">\n<p data-start=\"6295\" data-end=\"6332\">a <strong data-start=\"6297\" data-end=\"6332\">gunt\u014d koshirae militar de la \u00e9poca de guerra<\/strong><\/p>\n<\/li>\n<\/ul>\n<p data-start=\"6334\" data-end=\"6488\">Es una categor\u00eda muy codiciada tanto por los coleccionistas de espadas japonesas como por los de objetos militares japoneses, precisamente por esa doble identidad hist\u00f3rica.\n<\/p>\n<hr data-start=\"6490\" data-end=\"6493\" \/>\n<h3 data-start=\"6495\" data-end=\"6504\">Hoja<\/h3>\n<p data-start=\"6506\" data-end=\"6712\">Wakizashi con un <strong data-start=\"6524\" data-end=\"6567\">elegante sugata y curvatura pronunciada<\/strong>, que ofrece una fuerte presencia visual y un perfil general claramente tradicional. El <strong data-start=\"6648\" data-end=\"6663\">2,0 cm de sori<\/strong> le confiere una silueta din\u00e1mica y muy atractiva.\n<\/p>\n<p data-start=\"6714\" data-end=\"6890\">El <strong data-start=\"6718\" data-end=\"6737\">el nakago es mumei<\/strong> y muestra <strong data-start=\"6748\" data-end=\"6766\">dos mekugi-ana<\/strong>, totalmente coherente con una hoja antigua que ha pasado por una larga historia de montaje y posterior adaptaci\u00f3n para uso militar.\n<\/p>\n<p data-start=\"6892\" data-end=\"7286\">La hoja conserva un gran atractivo hist\u00f3rico como pieza antigua reutilizada en un contexto b\u00e9lico del siglo XX. Presenta desgaste propio de la edad y el uso, coherente con una hoja aut\u00e9ntica con una historia real, lo cual es completamente normal para este tipo de ejemplar. En conjunto, posee un valor significativo como <strong data-start=\"7193\" data-end=\"7285\">pieza hist\u00f3rica de transici\u00f3n entre la tradici\u00f3n familiar de espadas y el servicio militar moderno<\/strong>.<\/p>\n<hr data-start=\"7288\" data-end=\"7291\" \/>\n<h3 data-start=\"7293\" data-end=\"7367\">Koshirae y coherencia hist\u00f3rica (montaje militar de la Segunda Guerra Mundial)<\/h3>\n<p data-start=\"7369\" data-end=\"7476\">El montaje corresponde a una <strong data-start=\"7399\" data-end=\"7435\">configuraci\u00f3n gunt\u014d del per\u00edodo Sh\u014dwa<\/strong>, con caracter\u00edsticas t\u00edpicas de servicio\/campa\u00f1a:<\/p>\n<ul data-start=\"7478\" data-end=\"7753\">\n<li data-start=\"7478\" data-end=\"7520\">\n<p data-start=\"7480\" data-end=\"7520\"><strong data-start=\"7480\" data-end=\"7489\">Tsuka<\/strong> con <strong data-start=\"7495\" data-end=\"7520\">tsuka-ito marr\u00f3n\/caqui<\/strong><\/p>\n<\/li>\n<li data-start=\"7521\" data-end=\"7541\">\n<p data-start=\"7523\" data-end=\"7541\"><strong data-start=\"7523\" data-end=\"7541\">samegawa blanco<\/strong><\/p>\n<\/li>\n<li data-start=\"7542\" data-end=\"7561\">\n<p data-start=\"7544\" data-end=\"7561\"><strong data-start=\"7544\" data-end=\"7561\">menuki floral<\/strong><\/p>\n<\/li>\n<li data-start=\"7562\" data-end=\"7627\">\n<p data-start=\"7564\" data-end=\"7627\"><strong data-start=\"7564\" data-end=\"7592\">kashira con anillo sarute<\/strong>, caracter\u00edstico del servicio militar Monturas<\/p>\n<\/li>\n<li data-start=\"7628\" data-end=\"7684\">\n<p data-start=\"7630\" data-end=\"7684\"><strong data-start=\"7630\" data-end=\"7661\">Accesorios de lat\u00f3n\/tono dorado<\/strong> Con decoraci\u00f3n floral<\/p>\n<\/li>\n<li data-start=\"7685\" data-end=\"7753\">\n<p data-start=\"7687\" data-end=\"7753\"><strong data-start=\"7687\" data-end=\"7707\">Sistema de retenci\u00f3n<\/strong> Cerca de la tsuba, t\u00edpico de las monturas militares<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"7755\" data-end=\"8059\">El <strong data-start=\"7759\" data-end=\"7767\">saya<\/strong> Incluye una <strong data-start=\"7785\" data-end=\"7824\">Funda de cuero cosida para uso militar\/de campo<\/strong> con un <strong data-start=\"7832\" data-end=\"7851\">anillo de suspensi\u00f3n<\/strong>, una soluci\u00f3n pr\u00e1ctica estrechamente ligada al uso militar real. Este detalle aumenta significativamente el atractivo comercial de la pieza, ya que refuerza su identidad como un montaje apto para el servicio.<\/p>\n<p data-start=\"8061\" data-end=\"8196\">Desde un punto de vista hist\u00f3rico-comercial, el conjunto es muy coherente:<br data-start=\"8129\" data-end=\"8132\" \/><strong data-start=\"8132\" data-end=\"8195\">Hoja tradicional antigua + montaje militar funcional de tiempos de guerra<\/strong>.<\/p>\n<hr data-start=\"8198\" data-end=\"8201\" \/>\n<h3 data-start=\"8203\" data-end=\"8266\">Acerca de este tipo de pieza (reliquias familiares y uso en tiempos de guerra)<\/h3>\n<p data-start=\"8268\" data-end=\"8525\">Este tipo de wakizashi\/katana con montura militar refleja una realidad hist\u00f3rica bien conocida en el Jap\u00f3n de la Segunda Guerra Mundial: <strong data-start=\"8386\" data-end=\"8429\">muchos oficiales portaban espadas familiares antiguas<\/strong> (koto o shint\u014d) montadas como gunt\u014d, en lugar de llevar \u00fanicamente espadas modernas de producci\u00f3n militar.<\/p>\n<p data-start=\"8527\" data-end=\"8954\">En muchos casos, la espada era una <strong data-start=\"8558\" data-end=\"8577\">reliquia familiar<\/strong> entregada a un hijo que part\u00eda al frente, portando ideas de <strong data-start=\"8631\" data-end=\"8674\">linaje, honor y protecci\u00f3n simb\u00f3lica<\/strong>. En otros casos, tambi\u00e9n se adquir\u00edan espadas antiguas y se volv\u00edan a montar para el servicio. Precisamente por eso estas piezas son tan atractivas en el mercado actual: no son solo objetos militares, sino <strong data-start=\"8852\" data-end=\"8889\">nihont\u014d con biograf\u00eda hist\u00f3rica<\/strong>, que vinculan el Jap\u00f3n feudal con el Jap\u00f3n del siglo XX en un solo objeto.<\/p>\n<hr data-start=\"8956\" data-end=\"8959\" \/>\n<h3 data-start=\"8961\" data-end=\"8981\">Piezas auxiliares<\/h3>\n<p data-start=\"8983\" data-end=\"9174\">Una <strong data-start=\"8985\" data-end=\"9015\">Funda de cuero para combate\/campo<\/strong> La funda para la saya est\u00e1 presente y forma parte integral de la identidad hist\u00f3rica del conjunto, lo que le confiere un gran atractivo comercial como parte del montaje militar de la \u00e9poca de guerra.\n<\/p>\n<hr data-start=\"9248\" data-end=\"9251\" \/>\n<h3 data-start=\"9253\" data-end=\"9272\">Ficha t\u00e9cnica<\/h3>\n<p data-start=\"9274\" data-end=\"9744\"><strong data-start=\"9274\" data-end=\"9282\">Tipo<\/strong>: Wakizashi<br data-start=\"9293\" data-end=\"9296\" \/><strong data-start=\"9296\" data-end=\"9309\">Firma<\/strong>: Mumei (sin firmar)<br data-start=\"9327\" data-end=\"9330\" \/><strong data-start=\"9330\" data-end=\"9346\">Per\u00edodo de la hoja<\/strong>: Hoja antigua (finales de Muromachi \/ principios de Edo)<br data-start=\"9386\" data-end=\"9389\" \/><strong data-start=\"9389\" data-end=\"9401\">Montaje<\/strong>: Gunt\u014d (era Sh\u014dwa, Segunda Guerra Mundial)<br data-start=\"9438\" data-end=\"9441\" \/><strong data-start=\"9441\" data-end=\"9466\">Longitud de la hoja (nagasa)<\/strong>: 53,4 cm<br data-start=\"9475\" data-end=\"9478\" \/><strong data-start=\"9478\" data-end=\"9498\">Curvatura (sori)<\/strong>: 2,0 cm<br data-start=\"9506\" data-end=\"9509\" \/><strong data-start=\"9509\" data-end=\"9523\">mekugi-ana<\/strong>: 2 (visible)<br data-start=\"9536\" data-end=\"9539\" \/><strong data-start=\"9632\" data-end=\"9658\">Principal atractivo para coleccionistas<\/strong>: combinaci\u00f3n de una <strong data-start=\"9678\" data-end=\"9699\">antigua espada nihont\u014d<\/strong> y un <strong data-start=\"9707\" data-end=\"9744\">montura militar original de la \u00e9poca<\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>DESCRIPCI\u00d3N DEL ART\u00cdCULO: Incluye kimono o bolsa de algod\u00f3n. Incluye certificado de autenticidad de Nihonto. Incluye copia del Tokosusho. Documentaci\u00f3n \u9283\u7832\u5200\u5263\u985e\u767b\u9332\u8a3cCertificado de registro de armas de fuego y espadas \u5200\u5263\u985e \/ \u5200\u5263 \/ \u7a2e\u5225: \u308f\u304d\u3056\u3057Clasificaci\u00f3n de espada: Wakizashi \u9577\u3055: \u4e94\u4e09\u30fb\u56db\u30bb\u30f3\u30c1\u30e1\u30fc\u30c8\u30ebLongitud de la hoja: 53,4 cm \u53cd\u308a: \u4e8c\u30fb\u3007\u30bb\u30f3\u30c1\u30e1\u30fc\u30c8\u30ebCurvatura (sori): 2,0 cm \u76ee\u304f\u304e\u7a74: (la anotaci\u00f3n manuscrita es irregular en el documento)La hoja muestra claramente: dos mekugi-ana (dos orificios para clavijas). \u9298\u6587: \u7121\u9298Firma\/inscripci\u00f3n: Mumei (sin firmar) \u611b\u5a9b\u770c\u6559\u80b2\u59d4\u54e1\u4f1aAutoridad emisora: \u00a0Junta de Educaci\u00f3n Prefectural Smith \/ escuela \/ per\u00edodo y contexto Mumei (sin firmar)Esta es una antigua hoja japonesa, con una cronolog\u00eda de mercado y caracter\u00edsticas tipol\u00f3gicas consistentes con el finales del per\u00edodo Muromachi \/ principios del per\u00edodo Edo, posteriormente remontada en un koshirae militar japon\u00e9s de la era Sh\u014dwa (Segunda Guerra Mundial). Este tipo de ensamblaje es especialmente atractivo porque combina dos campos de coleccionismo en un solo objeto: una antigua tradicional nihont\u014d a gunt\u014d koshirae militar de la \u00e9poca de guerra Es una categor\u00eda muy codiciada tanto por los coleccionistas de espadas japonesas como por los de objetos militares japoneses, precisamente por esa doble identidad hist\u00f3rica. Hoja Wakizashi con un elegante sugata y curvatura pronunciada, que ofrece una fuerte presencia visual y un perfil general claramente tradicional. El 2,0 cm de sori le confiere una silueta din\u00e1mica y muy atractiva. El el nakago es mumei y muestra dos mekugi-ana, totalmente coherente con una hoja antigua que ha pasado por una larga historia de montaje y posterior adaptaci\u00f3n para uso militar. La hoja conserva un gran atractivo hist\u00f3rico como pieza antigua reutilizada en un contexto b\u00e9lico del siglo XX. Presenta desgaste propio de la edad y el uso, coherente con una hoja aut\u00e9ntica con una historia real, lo cual es completamente normal para este tipo de ejemplar. En conjunto, posee un valor significativo como pieza hist\u00f3rica de transici\u00f3n entre la tradici\u00f3n familiar de espadas y el servicio militar moderno. Koshirae y coherencia hist\u00f3rica (montaje militar de la Segunda Guerra Mundial) El montaje corresponde a una configuraci\u00f3n gunt\u014d del per\u00edodo Sh\u014dwa, con caracter\u00edsticas t\u00edpicas de servicio\/campa\u00f1a: Tsuka con tsuka-ito marr\u00f3n\/caqui samegawa blanco menuki floral kashira con anillo sarute, caracter\u00edstico del servicio militar Monturas Accesorios de lat\u00f3n\/tono dorado Con decoraci\u00f3n floral Sistema de retenci\u00f3n Cerca de la tsuba, t\u00edpico de las monturas militares El saya Incluye una Funda de cuero cosida para uso militar\/de campo con un anillo de suspensi\u00f3n, una soluci\u00f3n pr\u00e1ctica estrechamente ligada al uso militar real. Este detalle aumenta significativamente el atractivo comercial de la pieza, ya que refuerza su identidad como un montaje apto para el servicio. Desde un punto de vista hist\u00f3rico-comercial, el conjunto es muy coherente:Hoja tradicional antigua + montaje militar funcional de tiempos de guerra. Acerca de este tipo de pieza (reliquias familiares y uso en tiempos de guerra) Este tipo de wakizashi\/katana con montura militar refleja una realidad hist\u00f3rica bien conocida en el Jap\u00f3n de la Segunda Guerra Mundial: muchos oficiales portaban espadas familiares antiguas (koto o shint\u014d) montadas como gunt\u014d, en lugar de llevar \u00fanicamente espadas modernas de producci\u00f3n militar. En muchos casos, la espada era una reliquia familiar entregada a un hijo que part\u00eda al frente, portando ideas de linaje, honor y protecci\u00f3n simb\u00f3lica. En otros casos, tambi\u00e9n se adquir\u00edan espadas antiguas y se volv\u00edan a montar para el servicio. Precisamente por eso estas piezas son tan atractivas en el mercado actual: no son solo objetos militares, sino nihont\u014d con biograf\u00eda hist\u00f3rica, que vinculan el Jap\u00f3n feudal con el Jap\u00f3n del siglo XX en un solo objeto. Piezas auxiliares Una Funda de cuero para combate\/campo La funda para la saya est\u00e1 presente y forma parte integral de la identidad hist\u00f3rica del conjunto, lo que le confiere un gran atractivo comercial como parte del montaje militar de la \u00e9poca de guerra. Ficha t\u00e9cnica Tipo: WakizashiFirma: Mumei (sin firmar)Per\u00edodo de la hoja: Hoja antigua (finales de Muromachi \/ principios de Edo)Montaje: Gunt\u014d (era Sh\u014dwa, Segunda Guerra Mundial)Longitud de la hoja (nagasa): 53,4 cmCurvatura (sori): 2,0 cmmekugi-ana: 2 (visible)Principal atractivo para coleccionistas: combinaci\u00f3n de una antigua espada nihont\u014d y un montura militar original de la \u00e9poca<\/p>\n","protected":false},"featured_media":995010,"template":"","meta":[],"product_brand":[],"product_cat":[1078,1081],"product_tag":[1098,1109],"class_list":["post-995009","product","type-product","status-publish","has-post-thumbnail","product_cat-nihonto","product_cat-wakizashi","product_tag-katana","product_tag-nihonto","first","outofstock","featured","sold-individually","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wakizashi nihont\u014d con koshirae de la Segunda Guerra Mundial - Supein Nihonto<\/title>\n<meta name=\"description\" content=\"Wakizashi con un elegante sugata y una marcada curvatura, que ofrece una fuerte presencia visual y un perfil general claramente tradicional. El sori de 2,0 cm le confiere una silueta din\u00e1mica y muy atractiva. El nakago es mumei y presenta dos mekugi-ana, lo cual es totalmente coherente con una hoja antigua que ha pasado por una larga historia de montaje y posterior adaptaci\u00f3n para uso militar. La hoja conserva una fuerte hist.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/supeinnihonto.com\/es\/producto\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wakizashi nihont\u014d con koshirae de la Segunda Guerra Mundial - Supein Nihonto\" \/>\n<meta property=\"og:description\" content=\"Wakizashi con un elegante sugata y una marcada curvatura, que ofrece una fuerte presencia visual y un perfil general claramente tradicional. El sori de 2,0 cm le confiere una silueta din\u00e1mica y muy atractiva. El nakago es mumei y presenta dos mekugi-ana, lo cual es totalmente coherente con una hoja antigua que ha pasado por una larga historia de montaje y posterior adaptaci\u00f3n para uso militar. La hoja conserva una fuerte hist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/supeinnihonto.com\/es\/producto\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/\" \/>\n<meta property=\"og:site_name\" content=\"Supein Nihonto\" \/>\n<meta property=\"og:image\" content=\"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/GEO1028-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\\\/\",\"name\":\"Wakizashi nihont\u014d con koshirae de la Segunda Guerra Mundial - Supein Nihonto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GEO1028-scaled-1.jpg\",\"datePublished\":\"2026-05-23T08:19:56+00:00\",\"description\":\"Wakizashi con un elegante sugata y una marcada curvatura, que ofrece una fuerte presencia visual y un perfil general claramente tradicional. El sori de 2,0 cm le confiere una silueta din\u00e1mica y muy atractiva. El nakago es mumei y presenta dos mekugi-ana, lo cual es totalmente coherente con una hoja antigua que ha pasado por una larga historia de montaje y posterior adaptaci\u00f3n para uso militar. La hoja conserva una fuerte hist.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GEO1028-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/GEO1028-scaled-1.jpg\",\"width\":2560,\"height\":1704,\"caption\":\"Gunto wakizashi second world war for sale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wakizashi nihont\u014d con koshirae de la Segunda Guerra Mundial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"name\":\"Supein Nihonto\",\"description\":\"Authentic japanese Nihonto katana\",\"publisher\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/supeinnihonto.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\",\"name\":\"SupeinNihonto\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"width\":400,\"height\":400,\"caption\":\"SupeinNihonto\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wakizashi nihont\u014d con koshirae de la Segunda Guerra Mundial - Supein Nihonto","description":"Wakizashi con un elegante sugata y una marcada curvatura, que ofrece una fuerte presencia visual y un perfil general claramente tradicional. El sori de 2,0 cm le confiere una silueta din\u00e1mica y muy atractiva. El nakago es mumei y presenta dos mekugi-ana, lo cual es totalmente coherente con una hoja antigua que ha pasado por una larga historia de montaje y posterior adaptaci\u00f3n para uso militar. La hoja conserva una fuerte hist.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/supeinnihonto.com\/es\/producto\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/","og_locale":"es_ES","og_type":"article","og_title":"Wakizashi nihont\u014d con koshirae de la Segunda Guerra Mundial - Supein Nihonto","og_description":"Wakizashi con un elegante sugata y una marcada curvatura, que ofrece una fuerte presencia visual y un perfil general claramente tradicional. El sori de 2,0 cm le confiere una silueta din\u00e1mica y muy atractiva. El nakago es mumei y presenta dos mekugi-ana, lo cual es totalmente coherente con una hoja antigua que ha pasado por una larga historia de montaje y posterior adaptaci\u00f3n para uso militar. La hoja conserva una fuerte hist.","og_url":"https:\/\/supeinnihonto.com\/es\/producto\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/","og_site_name":"Supein Nihonto","og_image":[{"width":2560,"height":1704,"url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/GEO1028-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/supeinnihonto.com\/es\/producto\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/","url":"https:\/\/supeinnihonto.com\/es\/producto\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/","name":"Wakizashi nihont\u014d con koshirae de la Segunda Guerra Mundial - Supein Nihonto","isPartOf":{"@id":"https:\/\/supeinnihonto.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/supeinnihonto.com\/es\/producto\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/#primaryimage"},"image":{"@id":"https:\/\/supeinnihonto.com\/es\/producto\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/#primaryimage"},"thumbnailUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/GEO1028-scaled-1.jpg","datePublished":"2026-05-23T08:19:56+00:00","description":"Wakizashi con un elegante sugata y una marcada curvatura, que ofrece una fuerte presencia visual y un perfil general claramente tradicional. El sori de 2,0 cm le confiere una silueta din\u00e1mica y muy atractiva. El nakago es mumei y presenta dos mekugi-ana, lo cual es totalmente coherente con una hoja antigua que ha pasado por una larga historia de montaje y posterior adaptaci\u00f3n para uso militar. La hoja conserva una fuerte hist.","breadcrumb":{"@id":"https:\/\/supeinnihonto.com\/es\/producto\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/supeinnihonto.com\/es\/producto\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/es\/producto\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/#primaryimage","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/GEO1028-scaled-1.jpg","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/GEO1028-scaled-1.jpg","width":2560,"height":1704,"caption":"Gunto wakizashi second world war for sale"},{"@type":"BreadcrumbList","@id":"https:\/\/supeinnihonto.com\/es\/producto\/wakizashi-nihonto-con-koshirae-de-la-segunda-guerra-mundial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/supeinnihonto.com\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/supeinnihonto.com\/tienda\/"},{"@type":"ListItem","position":3,"name":"Wakizashi nihont\u014d con koshirae de la Segunda Guerra Mundial"}]},{"@type":"WebSite","@id":"https:\/\/supeinnihonto.com\/#website","url":"https:\/\/supeinnihonto.com\/","name":"Supein Nihonto","description":"Authentic japanese Nihonto katana","publisher":{"@id":"https:\/\/supeinnihonto.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/supeinnihonto.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/supeinnihonto.com\/#organization","name":"SupeinNihonto","url":"https:\/\/supeinnihonto.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","width":400,"height":400,"caption":"SupeinNihonto"},"image":{"@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/995009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/995009\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media\/995010"}],"wp:attachment":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media?parent=995009"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_brand?post=995009"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_cat?post=995009"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_tag?post=995009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}