{"id":994829,"date":"2026-05-23T08:21:09","date_gmt":"2026-05-23T08:21:09","guid":{"rendered":"https:\/\/supeinnihonto.com\/product\/katana-nihonto-con-koshirae-oscuro\/"},"modified":"2026-05-23T08:21:09","modified_gmt":"2026-05-23T08:21:09","slug":"katana-nihonto-con-koshirae-oscuro","status":"publish","type":"product","link":"https:\/\/supeinnihonto.com\/es\/producto\/katana-nihonto-con-koshirae-oscuro\/","title":{"rendered":"Katana nihont\u014d con koshirae oscuro"},"content":{"rendered":"<p><span>DESCRIPCI\u00d3N DEL ART\u00cdCULO:<\/span><\/p>\n<p>Incluye kimono o bolsa de algod\u00f3n. Incluye certificado de autenticidad (Supein Nihonto). Incluye copia del Tokorusho.<\/p>\n<div class=\"TyagGW_tableContainer\">\n<h3 data-section-id=\"8q6zro\" data-start=\"5993\" data-end=\"6010\">Documentaci\u00f3n<\/h3>\n<p data-start=\"4365\" data-end=\"4405\">Lectura y traducci\u00f3n del documento:<\/p>\n<p data-start=\"4533\" data-end=\"4660\"><strong data-start=\"4533\" data-end=\"4542\">Tipo:<\/strong> Katana<br data-start=\"4549\" data-end=\"4552\" \/><strong data-start=\"4552\" data-end=\"4569\">Longitud de la hoja:<\/strong> 69,6 cm<br data-start=\"4577\" data-end=\"4580\" \/><strong data-start=\"4580\" data-end=\"4601\">Curvatura (sori):<\/strong> 1,0 cm<br data-start=\"4608\" data-end=\"4611\" \/><strong data-start=\"4611\" data-end=\"4626\">Mekugi-ana:<\/strong> 3<br data-start=\"4628\" data-end=\"4631\" \/><strong data-start=\"4631\" data-end=\"4645\">Firma:<\/strong> \u7121\u9298 \u2014 <strong data-start=\"4651\" data-end=\"4660\">mumei<\/strong><\/p>\n<p data-start=\"4662\" data-end=\"4672\"><strong data-start=\"4662\" data-end=\"4672\">Per\u00edodo<\/strong><\/p>\n<p data-start=\"4674\" data-end=\"4990\">Japonesa <strong data-start=\"4683\" data-end=\"4692\">mumei<\/strong> Katana, catalogable como: <strong data-start=\"4717\" data-end=\"4774\">Finales del per\u00edodo Muromachi o principios del per\u00edodo Edo, siglos XVI-XVII<\/strong>La hoja presenta una silueta muy sobria, con una curvatura moderada y una presencia equilibrada, funcional y marcial, en plena consonancia con la artesan\u00eda de finales del per\u00edodo Muromachi y la transici\u00f3n a principios del per\u00edodo Edo. <\/p>\n<p data-start=\"4992\" data-end=\"5001\"><strong data-start=\"4992\" data-end=\"5001\">Hoja<\/strong><\/p>\n<p data-start=\"5003\" data-end=\"5240\">La espada muestra un <strong data-start=\"5021\" data-end=\"5049\">sugata limpio y elegante,<\/strong>con buena longitud y proporciones generales muy atractivas. La curvatura es moderada, lo que produce una l\u00ednea sobria, pr\u00e1ctica y bien definida. El kissaki tiene la forma adecuada y es visualmente impactante.\n<\/p>\n<p data-start=\"5242\" data-end=\"5595\">El <strong data-start=\"5246\" data-end=\"5255\">hamon visible<\/strong> es claramente visible y agradable, desarroll\u00e1ndose en un <strong data-start=\"5305\" data-end=\"5343\">Gunome-midare con tendencia a notare<\/strong>, creando una l\u00ednea de temple din\u00e1mica, ondulada y org\u00e1nica a lo largo del filo. Posee dinamismo, personalidad y un gran atractivo visual. En la zona del kissaki, el endurecimiento se extiende de forma coherente hasta el boshi, reforzando la buena impresi\u00f3n general de la hoja.\n<\/p>\n<p data-start=\"5597\" data-end=\"5858\">El <strong data-start=\"5601\" data-end=\"5611\">jihada<\/strong>\u00a0La superficie conserva una apariencia muy respetable y una lectura visual atractiva dentro del pulido actual. Toda la hoja transmite autenticidad, antig\u00fcedad y una est\u00e9tica cl\u00e1sica japonesa bien conservada.\n<\/p>\n<p data-start=\"5860\" data-end=\"6147\">El <strong data-start=\"5864\" data-end=\"5874\">nakago<\/strong>, con <strong data-start=\"5881\" data-end=\"5901\">tres mekugi-ana<\/strong> una p\u00e1tina antigua bien establecida, que le confiere a la pieza un fuerte sentido de historia. A lo largo de la <strong data-start=\"5996\" data-end=\"6004\">mune<\/strong>, se observa <strong data-start=\"6015\" data-end=\"6038\">una ligera oxidaci\u00f3n antigua<\/strong>, discreta y totalmente integrada al car\u00e1cter de la espada, sin perjudicar en absoluto su presentaci\u00f3n.\n<\/p>\n<p data-start=\"6149\" data-end=\"6161\"><strong data-start=\"6149\" data-end=\"6161\">Koshirae<\/strong><\/p>\n<p data-start=\"6163\" data-end=\"6293\">La katana viene acompa\u00f1ada de un <strong data-start=\"6194\" data-end=\"6215\">koshirae completo<\/strong> de aspecto oscuro y refinado, muy coherente con el car\u00e1cter de la hoja.\n<\/p>\n<p data-start=\"6295\" data-end=\"6679\">El <strong data-start=\"6299\" data-end=\"6307\">saya<\/strong>, con acabado en laca negra brillante, que confiere a la espada una identidad visual sobria y elegante. El <strong data-start=\"6400\" data-end=\"6409\">tsuka<\/strong>, envuelto en <strong data-start=\"6422\" data-end=\"6441\">tsuka-ito negro<\/strong> sobre <strong data-start=\"6447\" data-end=\"6465\">samegawa claro<\/strong>, conserva el contraste cl\u00e1sico que siempre funciona tan bien en monturas serias y distinguidas. <strong data-start=\"6568\" data-end=\"6583\">Menuki dorado<\/strong> introduce un sutil acento decorativo que enriquece el conjunto sin alterar su equilibrio.\n<\/p>\n<p data-start=\"6681\" data-end=\"7081\">El <strong data-start=\"6685\" data-end=\"6694\">fuchi<\/strong> presenta una decoraci\u00f3n floral en relieve con detalles dorados, delicada y bien integrada. <strong data-start=\"6782\" data-end=\"6791\">tsuba<\/strong>, de hierro y forma redondeada, tiene una s\u00f3lida presencia cl\u00e1sica, con una decoraci\u00f3n en relieve que complementa muy bien el resto de la montura. <strong data-start=\"6931\" data-end=\"6941\">habaki<\/strong>, en tono dorado, remata la base de la hoja de forma convincente y completa un montaje visualmente impactante, muy atractivo para coleccionistas.\n<\/p>\n<p data-start=\"7083\" data-end=\"7300\">Este <strong data-start=\"7088\" data-end=\"7100\">koshirae<\/strong>, adem\u00e1s de proteger la espada, le confiere cuerpo, identidad y presencia. Comparado con la austera desnudez de una shirasaya, este montaje posee peso visual, encanto hist\u00f3rico y un claro atractivo para la exhibici\u00f3n.\n<\/p>\n<p data-start=\"7302\" data-end=\"7316\"><strong data-start=\"7302\" data-end=\"7316\">Conclusi\u00f3n<\/strong><\/p>\n<p data-start=\"7318\" data-end=\"7735\">Esta es una <strong data-start=\"7328\" data-end=\"7388\">katana mumei del per\u00edodo Muromachi tard\u00edo al per\u00edodo Edo temprano<\/strong>, con una presencia directa, cl\u00e1sica y claramente japonesa. Su longitud, el hamon visible, el antiguo nakago de tres agujeros y el elegante koshirae completo se combinan para crear una pieza de gran atractivo visual y comercial. Es una pieza que atrae la mirada de inmediato, a la vez que conserva la autenticidad y la antig\u00fcedad que los coleccionistas serios valoran enormemente. <\/p>\n<p data-start=\"7737\" data-end=\"7756\"><strong data-start=\"7737\" data-end=\"7756\">Ficha t\u00e9cnica<\/strong><\/p>\n<p data-start=\"7758\" data-end=\"8263\">katana japonesa<br data-start=\"7773\" data-end=\"7776\" \/>Mumei<br data-start=\"7781\" data-end=\"7784\" \/>Per\u00edodo: finales de Muromachi \u2013 principios de Edo, siglos XVI-XVII<br data-start=\"7837\" data-end=\"7840\" \/>Nagasa: 69,6 cm.<br data-start=\"7915\" data-end=\"7918\" \/>Soros: 1,0 cm<br data-start=\"7930\" data-end=\"7933\" \/>Mekugi-ana: 3<br data-start=\"7946\" data-end=\"7949\" \/>Hamon: gunome-midare con tendencia notare<br data-start=\"7990\" data-end=\"7993\" \/>Nakago: p\u00e1tina antigua, 3 mekugi-ana<br data-start=\"8025\" data-end=\"8028\" \/>Estado: buena presentaci\u00f3n general; Ligera oxidaci\u00f3n antigua y discreta en el mune<br data-start=\"8107\" data-end=\"8110\" \/>Montaje: koshirae completo<br data-start=\"8137\" data-end=\"8140\" \/>Saya: laca negra<br data-start=\"8159\" data-end=\"8162\" \/>Tsuka: tsuka-ito negro sobre samegawa claro<br data-start=\"8204\" data-end=\"8207\" \/>Tsuba: hierro con decoraci\u00f3n en relieve<br data-start=\"8241\" data-end=\"8244\" \/>Habaki: tono dorado<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>DESCRIPCI\u00d3N DEL ART\u00cdCULO: Incluye kimono o bolsa de algod\u00f3n. Incluye certificado de autenticidad (Supein Nihonto). Incluye copia del Tokorusho. Documentaci\u00f3n Lectura y traducci\u00f3n del documento: Tipo: KatanaLongitud de la hoja: 69,6 cmCurvatura (sori): 1,0 cmMekugi-ana: 3Firma: \u7121\u9298 \u2014 mumei Per\u00edodo Japonesa mumei Katana, catalogable como: Finales del per\u00edodo Muromachi o principios del per\u00edodo Edo, siglos XVI-XVIILa hoja presenta una silueta muy sobria, con una curvatura moderada y una presencia equilibrada, funcional y marcial, en plena consonancia con la artesan\u00eda de finales del per\u00edodo Muromachi y la transici\u00f3n a principios del per\u00edodo Edo. Hoja La espada muestra un sugata limpio y elegante,con buena longitud y proporciones generales muy atractivas. La curvatura es moderada, lo que produce una l\u00ednea sobria, pr\u00e1ctica y bien definida. El kissaki tiene la forma adecuada y es visualmente impactante. El hamon visible es claramente visible y agradable, desarroll\u00e1ndose en un Gunome-midare con tendencia a notare, creando una l\u00ednea de temple din\u00e1mica, ondulada y org\u00e1nica a lo largo del filo. Posee dinamismo, personalidad y un gran atractivo visual. En la zona del kissaki, el endurecimiento se extiende de forma coherente hasta el boshi, reforzando la buena impresi\u00f3n general de la hoja. El jihada\u00a0La superficie conserva una apariencia muy respetable y una lectura visual atractiva dentro del pulido actual. Toda la hoja transmite autenticidad, antig\u00fcedad y una est\u00e9tica cl\u00e1sica japonesa bien conservada. El nakago, con tres mekugi-ana una p\u00e1tina antigua bien establecida, que le confiere a la pieza un fuerte sentido de historia. A lo largo de la mune, se observa una ligera oxidaci\u00f3n antigua, discreta y totalmente integrada al car\u00e1cter de la espada, sin perjudicar en absoluto su presentaci\u00f3n. Koshirae La katana viene acompa\u00f1ada de un koshirae completo de aspecto oscuro y refinado, muy coherente con el car\u00e1cter de la hoja. El saya, con acabado en laca negra brillante, que confiere a la espada una identidad visual sobria y elegante. El tsuka, envuelto en tsuka-ito negro sobre samegawa claro, conserva el contraste cl\u00e1sico que siempre funciona tan bien en monturas serias y distinguidas. Menuki dorado introduce un sutil acento decorativo que enriquece el conjunto sin alterar su equilibrio. El fuchi presenta una decoraci\u00f3n floral en relieve con detalles dorados, delicada y bien integrada. tsuba, de hierro y forma redondeada, tiene una s\u00f3lida presencia cl\u00e1sica, con una decoraci\u00f3n en relieve que complementa muy bien el resto de la montura. habaki, en tono dorado, remata la base de la hoja de forma convincente y completa un montaje visualmente impactante, muy atractivo para coleccionistas. Este koshirae, adem\u00e1s de proteger la espada, le confiere cuerpo, identidad y presencia. Comparado con la austera desnudez de una shirasaya, este montaje posee peso visual, encanto hist\u00f3rico y un claro atractivo para la exhibici\u00f3n. Conclusi\u00f3n Esta es una katana mumei del per\u00edodo Muromachi tard\u00edo al per\u00edodo Edo temprano, con una presencia directa, cl\u00e1sica y claramente japonesa. Su longitud, el hamon visible, el antiguo nakago de tres agujeros y el elegante koshirae completo se combinan para crear una pieza de gran atractivo visual y comercial. Es una pieza que atrae la mirada de inmediato, a la vez que conserva la autenticidad y la antig\u00fcedad que los coleccionistas serios valoran enormemente. Ficha t\u00e9cnica katana japonesaMumeiPer\u00edodo: finales de Muromachi \u2013 principios de Edo, siglos XVI-XVIINagasa: 69,6 cm.Soros: 1,0 cmMekugi-ana: 3Hamon: gunome-midare con tendencia notareNakago: p\u00e1tina antigua, 3 mekugi-anaEstado: buena presentaci\u00f3n general; Ligera oxidaci\u00f3n antigua y discreta en el muneMontaje: koshirae completoSaya: laca negraTsuka: tsuka-ito negro sobre samegawa claroTsuba: hierro con decoraci\u00f3n en relieveHabaki: tono dorado<\/p>\n","protected":false},"featured_media":994830,"template":"","meta":[],"product_brand":[],"product_cat":[1079,1078],"product_tag":[1098,1109],"class_list":["post-994829","product","type-product","status-publish","has-post-thumbnail","product_cat-katana-tachi","product_cat-nihonto","product_tag-katana","product_tag-nihonto","first","outofstock","featured","sold-individually","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Katana nihont\u014d con koshirae oscuro - Supein Nihonto<\/title>\n<meta name=\"description\" content=\"La espada presenta una sugata limpia y elegante, con buena longitud y proporciones generales muy atractivas. Su curvatura moderada le confiere un aspecto sobrio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/supeinnihonto.com\/product\/nihonto-katana-dark-koshirae\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Katana nihont\u014d con koshirae oscuro - Supein Nihonto\" \/>\n<meta property=\"og:description\" content=\"La espada presenta una sugata limpia y elegante, con buena longitud y proporciones generales muy atractivas. Su curvatura moderada le confiere un aspecto sobrio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/supeinnihonto.com\/product\/nihonto-katana-dark-koshirae\/\" \/>\n<meta property=\"og:site_name\" content=\"Supein Nihonto\" \/>\n<meta property=\"og:image\" content=\"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/67604title-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1139\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-dark-koshirae\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-dark-koshirae\\\/\",\"name\":\"Katana nihont\u014d con koshirae oscuro - Supein Nihonto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-dark-koshirae\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-dark-koshirae\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/67604title-scaled.jpg\",\"datePublished\":\"2026-05-23T08:21:09+00:00\",\"description\":\"La espada presenta una sugata limpia y elegante, con buena longitud y proporciones generales muy atractivas. Su curvatura moderada le confiere un aspecto sobrio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-dark-koshirae\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-dark-koshirae\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-dark-koshirae\\\/#primaryimage\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/67604title-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/67604title-scaled.jpg\",\"width\":2560,\"height\":1139},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-dark-koshirae\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Katana nihont\u014d con koshirae oscuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"name\":\"Supein Nihonto\",\"description\":\"Authentic japanese Nihonto katana\",\"publisher\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/supeinnihonto.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\",\"name\":\"SupeinNihonto\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"width\":400,\"height\":400,\"caption\":\"SupeinNihonto\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Katana nihont\u014d con koshirae oscuro - Supein Nihonto","description":"La espada presenta una sugata limpia y elegante, con buena longitud y proporciones generales muy atractivas. Su curvatura moderada le confiere un aspecto sobrio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-dark-koshirae\/","og_locale":"es_ES","og_type":"article","og_title":"Katana nihont\u014d con koshirae oscuro - Supein Nihonto","og_description":"La espada presenta una sugata limpia y elegante, con buena longitud y proporciones generales muy atractivas. Su curvatura moderada le confiere un aspecto sobrio.","og_url":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-dark-koshirae\/","og_site_name":"Supein Nihonto","og_image":[{"width":2560,"height":1139,"url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/67604title-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-dark-koshirae\/","url":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-dark-koshirae\/","name":"Katana nihont\u014d con koshirae oscuro - Supein Nihonto","isPartOf":{"@id":"https:\/\/supeinnihonto.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-dark-koshirae\/#primaryimage"},"image":{"@id":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-dark-koshirae\/#primaryimage"},"thumbnailUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/67604title-scaled.jpg","datePublished":"2026-05-23T08:21:09+00:00","description":"La espada presenta una sugata limpia y elegante, con buena longitud y proporciones generales muy atractivas. Su curvatura moderada le confiere un aspecto sobrio.","breadcrumb":{"@id":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-dark-koshirae\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/supeinnihonto.com\/product\/nihonto-katana-dark-koshirae\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-dark-koshirae\/#primaryimage","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/67604title-scaled.jpg","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/67604title-scaled.jpg","width":2560,"height":1139},{"@type":"BreadcrumbList","@id":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-dark-koshirae\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/supeinnihonto.com\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/supeinnihonto.com\/tienda\/"},{"@type":"ListItem","position":3,"name":"Katana nihont\u014d con koshirae oscuro"}]},{"@type":"WebSite","@id":"https:\/\/supeinnihonto.com\/#website","url":"https:\/\/supeinnihonto.com\/","name":"Supein Nihonto","description":"Authentic japanese Nihonto katana","publisher":{"@id":"https:\/\/supeinnihonto.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/supeinnihonto.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/supeinnihonto.com\/#organization","name":"SupeinNihonto","url":"https:\/\/supeinnihonto.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","width":400,"height":400,"caption":"SupeinNihonto"},"image":{"@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/994829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/994829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media\/994830"}],"wp:attachment":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media?parent=994829"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_brand?post=994829"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_cat?post=994829"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_tag?post=994829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}