{"id":994462,"date":"2026-05-23T10:09:47","date_gmt":"2026-05-23T10:09:47","guid":{"rendered":"https:\/\/supeinnihonto.com\/product\/tsuba-marugata-firmada-por-la-escuela-shoten\/"},"modified":"2026-05-23T10:09:47","modified_gmt":"2026-05-23T10:09:47","slug":"tsuba-marugata-firmada-por-la-escuela-shoten","status":"publish","type":"product","link":"https:\/\/supeinnihonto.com\/es\/producto\/tsuba-marugata-firmada-por-la-escuela-shoten\/","title":{"rendered":"Tsuba marugata firmada por la escuela Sh\u014dten"},"content":{"rendered":"<p><strong>ART\u00cdCULO:<\/strong><\/p>\n<p>Incluye certificado de SupeinNihonto. Incluye caja de madera.<\/p>\n<p>TSUBA DE HIERRO JAPON\u00c9S CON RELIEVE FIGURATIVO E INCRUSTACIONES DE ORO<\/p>\n<p>Tsuba de hierro japonesa con una fina decoraci\u00f3n figurativa en alto relieve y detalles de incrustaciones de oro, que representa una din\u00e1mica escena marcial. La composici\u00f3n muestra a varios guerreros con armadura dispuestos en un paisaje rocoso bajo formas fluidas que sugieren nubes o terreno monta\u00f1oso, representados con un fuerte volumen escult\u00f3rico y un movimiento convincente.<\/p>\n<p>La superficie presenta una p\u00e1tina oscura bien desarrollada, con dorado selectivo que resalta los cascos, los elementos de la armadura y los detalles del fondo, produciendo el refinado contraste visual caracter\u00edstico de la artesan\u00eda de calidad del per\u00edodo Edo. La placa de hierro muestra un modelado a mano claro con textura org\u00e1nica, particularmente visible en el relieve y los pliegues de la composici\u00f3n.<\/p>\n<p>El nakago-ana es de forma est\u00e1ndar con hitsu-ana bien integrado. Una firma incisa verticalmente est\u00e1 presente en el seppa-dai. La lectura m\u00e1s plausible es S\u014dten saku (\u5b97\u5178\u4f5c) junto con una inscripci\u00f3n de residencia (probablemente Hikone-j\u016b), lo que sit\u00faa la pieza dentro de la escuela Hikone S\u014dten, famosa por sus tsuba samur\u00e1i narrativas con detalles dorados.<\/p>\n<p>Por su estilo, t\u00e9cnica y tem\u00e1tica, la guarda puede atribuirse con seguridad al per\u00edodo Edo, dentro de la producci\u00f3n decorativa de la tradici\u00f3n S\u014dten, muy apreciada por los coleccionistas por su v\u00edvida obra figurativa y su riqueza ornamental.<\/p>\n<p>Estado: en general bien conservada, con p\u00e1tina uniforme y leves signos de desgaste propios de la edad.<\/p>\n<p>7,4 x 7,0 cm<\/p>\n<p><strong>SOBRE NOSOTROS:<\/strong><\/p>\n<p><span>En Supein Nihonto nos esforzamos por ofrecerle espadas y armaduras samur\u00e1i de alta calidad a precios muy inferiores a los de la competencia. Probablemente seamos el mayor exportador de Europa y nos enorgullece anunciar que somos el vendedor n\u00famero uno en las subastas de samur\u00e1is y art\u00edculos japoneses de Catawiki. Esto es especialmente importante para ahorrar en impuestos y tiempos de espera que pueden superar los cuatro meses con los vendedores japoneses, adem\u00e1s de los engorrosos y a veces problem\u00e1ticos tr\u00e1mites que alargan a\u00fan m\u00e1s las entregas, incluso la devoluci\u00f3n del paquete a su origen y m\u00e1s del 35% adicional sobre el precio final debido a los aranceles, impuestos y tasas aduaneras que encarecen el producto pero no su calidad ni su futura reventa. Adem\u00e1s, somos vendedores profesionales y, por lo tanto, nuestra garant\u00eda de satisfacci\u00f3n, conocimiento y est\u00e1ndares son superiores a los de los vendedores particulares, con garant\u00edas posventa m\u00e1s altas. Gracias a esto y a los precios profesionales m\u00e1s bajos del sector, adem\u00e1s de nuestro m\u00e9todo de env\u00edo r\u00e1pido y eficiente que rara vez supera los tres d\u00edas de entrega en Europa, estamos seguros de que disfrutar\u00e1 de esta gran oportunidad de poseer una obra de arte que se revalorizar\u00e1 con el paso de los a\u00f1os y que representa una excelente inversi\u00f3n. Conf\u00ede en nosotros para disfrutar del arte samur\u00e1i.<br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ART\u00cdCULO: Incluye certificado de SupeinNihonto. Incluye caja de madera. TSUBA DE HIERRO JAPON\u00c9S CON RELIEVE FIGURATIVO E INCRUSTACIONES DE ORO Tsuba de hierro japonesa con una fina decoraci\u00f3n figurativa en alto relieve y detalles de incrustaciones de oro, que representa una din\u00e1mica escena marcial. La composici\u00f3n muestra a varios guerreros con armadura dispuestos en un paisaje rocoso bajo formas fluidas que sugieren nubes o terreno monta\u00f1oso, representados con un fuerte volumen escult\u00f3rico y un movimiento convincente. La superficie presenta una p\u00e1tina oscura bien desarrollada, con dorado selectivo que resalta los cascos, los elementos de la armadura y los detalles del fondo, produciendo el refinado contraste visual caracter\u00edstico de la artesan\u00eda de calidad del per\u00edodo Edo. La placa de hierro muestra un modelado a mano claro con textura org\u00e1nica, particularmente visible en el relieve y los pliegues de la composici\u00f3n. El nakago-ana es de forma est\u00e1ndar con hitsu-ana bien integrado. Una firma incisa verticalmente est\u00e1 presente en el seppa-dai. La lectura m\u00e1s plausible es S\u014dten saku (\u5b97\u5178\u4f5c) junto con una inscripci\u00f3n de residencia (probablemente Hikone-j\u016b), lo que sit\u00faa la pieza dentro de la escuela Hikone S\u014dten, famosa por sus tsuba samur\u00e1i narrativas con detalles dorados. Por su estilo, t\u00e9cnica y tem\u00e1tica, la guarda puede atribuirse con seguridad al per\u00edodo Edo, dentro de la producci\u00f3n decorativa de la tradici\u00f3n S\u014dten, muy apreciada por los coleccionistas por su v\u00edvida obra figurativa y su riqueza ornamental. Estado: en general bien conservada, con p\u00e1tina uniforme y leves signos de desgaste propios de la edad. 7,4 x 7,0 cm SOBRE NOSOTROS: En Supein Nihonto nos esforzamos por ofrecerle espadas y armaduras samur\u00e1i de alta calidad a precios muy inferiores a los de la competencia. Probablemente seamos el mayor exportador de Europa y nos enorgullece anunciar que somos el vendedor n\u00famero uno en las subastas de samur\u00e1is y art\u00edculos japoneses de Catawiki. Esto es especialmente importante para ahorrar en impuestos y tiempos de espera que pueden superar los cuatro meses con los vendedores japoneses, adem\u00e1s de los engorrosos y a veces problem\u00e1ticos tr\u00e1mites que alargan a\u00fan m\u00e1s las entregas, incluso la devoluci\u00f3n del paquete a su origen y m\u00e1s del 35% adicional sobre el precio final debido a los aranceles, impuestos y tasas aduaneras que encarecen el producto pero no su calidad ni su futura reventa. Adem\u00e1s, somos vendedores profesionales y, por lo tanto, nuestra garant\u00eda de satisfacci\u00f3n, conocimiento y est\u00e1ndares son superiores a los de los vendedores particulares, con garant\u00edas posventa m\u00e1s altas. Gracias a esto y a los precios profesionales m\u00e1s bajos del sector, adem\u00e1s de nuestro m\u00e9todo de env\u00edo r\u00e1pido y eficiente que rara vez supera los tres d\u00edas de entrega en Europa, estamos seguros de que disfrutar\u00e1 de esta gran oportunidad de poseer una obra de arte que se revalorizar\u00e1 con el paso de los a\u00f1os y que representa una excelente inversi\u00f3n. Conf\u00ede en nosotros para disfrutar del arte samur\u00e1i.<\/p>\n","protected":false},"featured_media":994463,"template":"","meta":[],"product_brand":[],"product_cat":[1083,1086],"product_tag":[1097,1098,1108,1138],"class_list":["post-994462","product","type-product","status-publish","has-post-thumbnail","product_cat-tosogu","product_cat-tsuba","product_tag-hozon","product_tag-katana","product_tag-nbthk","product_tag-tsuba","first","outofstock","sold-individually","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tsuba marugata firmada por la escuela Sh\u014dten - Supein Nihonto<\/title>\n<meta name=\"description\" content=\"Tsuba japonesa de hierro con una fina decoraci\u00f3n figurativa en alto relieve y detalles de incrustaciones de oro, que representa una din\u00e1mica escena marcial. La composici\u00f3n muestra a varios guerreros con armadura dispuestos en un paisaje rocoso bajo formas fluidas que sugieren nubes o terreno monta\u00f1oso, representados con un fuerte volumen escult\u00f3rico y un movimiento convincente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/supeinnihonto.com\/es\/producto\/tsuba-marugata-firmada-por-la-escuela-shoten\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tsuba marugata firmada por la escuela Sh\u014dten - Supein Nihonto\" \/>\n<meta property=\"og:description\" content=\"Tsuba japonesa de hierro con una fina decoraci\u00f3n figurativa en alto relieve y detalles de incrustaciones de oro, que representa una din\u00e1mica escena marcial. La composici\u00f3n muestra a varios guerreros con armadura dispuestos en un paisaje rocoso bajo formas fluidas que sugieren nubes o terreno monta\u00f1oso, representados con un fuerte volumen escult\u00f3rico y un movimiento convincente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/supeinnihonto.com\/es\/producto\/tsuba-marugata-firmada-por-la-escuela-shoten\/\" \/>\n<meta property=\"og:site_name\" content=\"Supein Nihonto\" \/>\n<meta property=\"og:image\" content=\"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/DSC_6430-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/tsuba-marugata-firmada-por-la-escuela-shoten\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/tsuba-marugata-firmada-por-la-escuela-shoten\\\/\",\"name\":\"Tsuba marugata firmada por la escuela Sh\u014dten - Supein Nihonto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/tsuba-marugata-firmada-por-la-escuela-shoten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/tsuba-marugata-firmada-por-la-escuela-shoten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DSC_6430-scaled-1.jpg\",\"datePublished\":\"2026-05-23T10:09:47+00:00\",\"description\":\"Tsuba japonesa de hierro con una fina decoraci\u00f3n figurativa en alto relieve y detalles de incrustaciones de oro, que representa una din\u00e1mica escena marcial. La composici\u00f3n muestra a varios guerreros con armadura dispuestos en un paisaje rocoso bajo formas fluidas que sugieren nubes o terreno monta\u00f1oso, representados con un fuerte volumen escult\u00f3rico y un movimiento convincente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/tsuba-marugata-firmada-por-la-escuela-shoten\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/tsuba-marugata-firmada-por-la-escuela-shoten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/tsuba-marugata-firmada-por-la-escuela-shoten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DSC_6430-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DSC_6430-scaled-1.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/tsuba-marugata-firmada-por-la-escuela-shoten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tsuba marugata firmada por la escuela Sh\u014dten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"name\":\"Supein Nihonto\",\"description\":\"Authentic japanese Nihonto katana\",\"publisher\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/supeinnihonto.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\",\"name\":\"SupeinNihonto\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"width\":400,\"height\":400,\"caption\":\"SupeinNihonto\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tsuba marugata firmada por la escuela Sh\u014dten - Supein Nihonto","description":"Tsuba japonesa de hierro con una fina decoraci\u00f3n figurativa en alto relieve y detalles de incrustaciones de oro, que representa una din\u00e1mica escena marcial. La composici\u00f3n muestra a varios guerreros con armadura dispuestos en un paisaje rocoso bajo formas fluidas que sugieren nubes o terreno monta\u00f1oso, representados con un fuerte volumen escult\u00f3rico y un movimiento convincente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/supeinnihonto.com\/es\/producto\/tsuba-marugata-firmada-por-la-escuela-shoten\/","og_locale":"es_ES","og_type":"article","og_title":"Tsuba marugata firmada por la escuela Sh\u014dten - Supein Nihonto","og_description":"Tsuba japonesa de hierro con una fina decoraci\u00f3n figurativa en alto relieve y detalles de incrustaciones de oro, que representa una din\u00e1mica escena marcial. La composici\u00f3n muestra a varios guerreros con armadura dispuestos en un paisaje rocoso bajo formas fluidas que sugieren nubes o terreno monta\u00f1oso, representados con un fuerte volumen escult\u00f3rico y un movimiento convincente.","og_url":"https:\/\/supeinnihonto.com\/es\/producto\/tsuba-marugata-firmada-por-la-escuela-shoten\/","og_site_name":"Supein Nihonto","og_image":[{"width":2560,"height":1707,"url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/DSC_6430-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/supeinnihonto.com\/es\/producto\/tsuba-marugata-firmada-por-la-escuela-shoten\/","url":"https:\/\/supeinnihonto.com\/es\/producto\/tsuba-marugata-firmada-por-la-escuela-shoten\/","name":"Tsuba marugata firmada por la escuela Sh\u014dten - Supein Nihonto","isPartOf":{"@id":"https:\/\/supeinnihonto.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/supeinnihonto.com\/es\/producto\/tsuba-marugata-firmada-por-la-escuela-shoten\/#primaryimage"},"image":{"@id":"https:\/\/supeinnihonto.com\/es\/producto\/tsuba-marugata-firmada-por-la-escuela-shoten\/#primaryimage"},"thumbnailUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/DSC_6430-scaled-1.jpg","datePublished":"2026-05-23T10:09:47+00:00","description":"Tsuba japonesa de hierro con una fina decoraci\u00f3n figurativa en alto relieve y detalles de incrustaciones de oro, que representa una din\u00e1mica escena marcial. La composici\u00f3n muestra a varios guerreros con armadura dispuestos en un paisaje rocoso bajo formas fluidas que sugieren nubes o terreno monta\u00f1oso, representados con un fuerte volumen escult\u00f3rico y un movimiento convincente.","breadcrumb":{"@id":"https:\/\/supeinnihonto.com\/es\/producto\/tsuba-marugata-firmada-por-la-escuela-shoten\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/supeinnihonto.com\/es\/producto\/tsuba-marugata-firmada-por-la-escuela-shoten\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/es\/producto\/tsuba-marugata-firmada-por-la-escuela-shoten\/#primaryimage","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/DSC_6430-scaled-1.jpg","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/DSC_6430-scaled-1.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/supeinnihonto.com\/es\/producto\/tsuba-marugata-firmada-por-la-escuela-shoten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/supeinnihonto.com\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/supeinnihonto.com\/tienda\/"},{"@type":"ListItem","position":3,"name":"Tsuba marugata firmada por la escuela Sh\u014dten"}]},{"@type":"WebSite","@id":"https:\/\/supeinnihonto.com\/#website","url":"https:\/\/supeinnihonto.com\/","name":"Supein Nihonto","description":"Authentic japanese Nihonto katana","publisher":{"@id":"https:\/\/supeinnihonto.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/supeinnihonto.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/supeinnihonto.com\/#organization","name":"SupeinNihonto","url":"https:\/\/supeinnihonto.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","width":400,"height":400,"caption":"SupeinNihonto"},"image":{"@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/994462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/994462\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media\/994463"}],"wp:attachment":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media?parent=994462"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_brand?post=994462"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_cat?post=994462"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_tag?post=994462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}