{"id":994247,"date":"2026-05-23T10:09:50","date_gmt":"2026-05-23T10:09:50","guid":{"rendered":"https:\/\/supeinnihonto.com\/product\/katana-nihonto-echizen-bonryu-con-doble-certificado-nbthk\/"},"modified":"2026-05-23T10:09:50","modified_gmt":"2026-05-23T10:09:50","slug":"katana-nihonto-echizen-bonryu-con-doble-certificado-nbthk","status":"publish","type":"product","link":"https:\/\/supeinnihonto.com\/es\/producto\/katana-nihonto-echizen-bonryu-con-doble-certificado-nbthk\/","title":{"rendered":"Katana nihont\u014d \u00abEchizen Bonry\u016b\u00bb con doble certificado NBTHK"},"content":{"rendered":"<p><span>DESCRIPCI\u00d3N DEL ART\u00cdCULO:<\/span><\/p>\n<p>Incluye kimono o bolsa de algod\u00f3n. Incluye certificado de autenticidad (Supein Nihonto). Incluye copia del certificado de autenticidad (Tokosusho). Incluye certificado NBTHK Tokobetsu kicho para la hoja y el koshirae.<\/p>\n<h3 data-start=\"2094\" data-end=\"2115\"><strong data-start=\"2098\" data-end=\"2115\">Documentaci\u00f3n<\/strong><\/h3>\n<p data-start=\"2117\" data-end=\"2330\"><strong data-start=\"2117\" data-end=\"2134\">NBTHK \u2014 Hoja<\/strong><br data-start=\"2134\" data-end=\"2137\" \/>Clasificaci\u00f3n: <strong data-start=\"2153\" data-end=\"2178\">Tokubetsu Kich\u014d Token<\/strong><br data-start=\"2178\" data-end=\"2181\" \/>Estado: <strong data-start=\"2189\" data-end=\"2198\">Mumei,<\/strong>\u00a0<strong data-start=\"2218\" data-end=\"2236\">Echizen Bonry\u016b<\/strong><br data-start=\"2236\" data-end=\"2239\" \/>Organismo emisor: <strong data-start=\"2294\" data-end=\"2330\">Nihon Bijutsu T\u014dken Hozon Ky\u014dkai<\/strong><\/p>\n<hr data-start=\"2332\" data-end=\"2335\" \/>\n<p data-start=\"2337\" data-end=\"2418\"><strong data-start=\"2337\" data-end=\"2357\">NBTHK\u2014 Koshirae<\/strong><\/p>\n<p data-start=\"2337\" data-end=\"2418\"><br data-start=\"2357\" data-end=\"2360\" \/>Clasificaci\u00f3n: <strong data-start=\"2376\" data-end=\"2395\">Tokubetsu Kich\u014d<\/strong><br data-start=\"2395\" data-end=\"2398\" \/>Objeto: <strong data-start=\"2406\" data-end=\"2418\">Koshirae<\/strong><\/p>\n<p data-start=\"2420\" data-end=\"2456\">Descripci\u00f3n literal por certificado:<\/p>\n<ul data-start=\"2457\" data-end=\"2539\">\n<li data-start=\"2457\" data-end=\"2499\">\n<p data-start=\"2459\" data-end=\"2499\"><strong data-start=\"2459\" data-end=\"2467\">Saya<\/strong>: negra <strong data-start=\"2475\" data-end=\"2489\">Kuro-roiro<\/strong> laca<\/p>\n<\/li>\n<li data-start=\"2500\" data-end=\"2539\">\n<p data-start=\"2502\" data-end=\"2539\"><strong data-start=\"2502\" data-end=\"2511\">Tsuba<\/strong>: hierro redondo (<strong data-start=\"2525\" data-end=\"2538\">Maru-gata<\/strong>)<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2541\" data-end=\"2632\">Fecha: <strong data-start=\"2547\" data-end=\"2579\">20 de febrero de 1967 (Sh\u014dwa 42)<\/strong><\/p>\n<p data-start=\"2541\" data-end=\"2632\"><br data-start=\"2579\" data-end=\"2582\" \/>Organismo emisor: <strong data-start=\"2596\" data-end=\"2632\">Nihon Bijutsu T\u014dken Hozon Ky\u014dkai<\/strong><\/p>\n<hr data-start=\"2634\" data-end=\"2637\" \/>\n<p data-start=\"2639\" data-end=\"2987\"><strong data-start=\"2639\" data-end=\"2676\">Registro japon\u00e9s \u2014 Torokusho<\/strong><\/p>\n<p data-start=\"2639\" data-end=\"2987\"><br data-start=\"2676\" data-end=\"2679\" \/>Certificado oficial de registro prefectural japon\u00e9s para una espada antigua.<br data-start=\"2755\" data-end=\"2758\" \/>Legal Documento administrativo con n\u00famero de registro y sellos oficiales que confirma el registro legal de la hoja como nihont\u014d.<br \/>\n<br data-start=\"2889\" data-end=\"2892\" \/>El torokusho no <strong data-start=\"2911\" data-end=\"2918\">no<\/strong> proporciona informaci\u00f3n sobre el forjador ni la escuela, m\u00e1s all\u00e1 del registro.\n<\/p>\n<hr data-start=\"2989\" data-end=\"2992\" \/>\n<h3 data-start=\"2994\" data-end=\"3008\"><strong data-start=\"2998\" data-end=\"3008\">Escuela<\/strong><\/h3>\n<p data-start=\"3010\" data-end=\"3181\"><strong data-start=\"3010\" data-end=\"3028\">Echizen Bonry\u016b<\/strong><\/p>\n<p data-start=\"3010\" data-end=\"3181\">Una escuela del per\u00edodo Edo documentada en la provincia de Echizen.<br \/>\n<br data-start=\"3083\" data-end=\"3086\" \/>La atribuci\u00f3n se <strong data-start=\"3105\" data-end=\"3126\">expl\u00edcitamente indicada<\/strong> en el certificado NBTHK Tokubetsu Kich\u014d de la hoja.\n<\/p>\n<hr data-start=\"3183\" data-end=\"3186\" \/>\n<h3 data-start=\"3188\" data-end=\"3202\"><strong data-start=\"3192\" data-end=\"3202\">Per\u00edodo<\/strong><\/h3>\n<p data-start=\"3204\" data-end=\"3218\"><strong data-start=\"3204\" data-end=\"3218\">Periodo Edo Medio (aprox. siglos XVII-XVIII)<\/strong><\/p>\n<hr data-start=\"3220\" data-end=\"3223\" \/>\n<h3 data-start=\"3225\" data-end=\"3259\"><strong data-start=\"3229\" data-end=\"3259\">Resumen t\u00e9cnico<\/strong><\/h3>\n<p data-start=\"3261\" data-end=\"3650\">Katana del periodo Edo con una <strong data-start=\"3286\" data-end=\"3350\">hoja mumei atribuida por la NBTHK a la escuela Echizen Bonry\u016b<\/strong>certificada como <strong data-start=\"3365\" data-end=\"3390\">Tokubetsu Kich\u014d Token<\/strong>.<br data-start=\"3391\" data-end=\"3394\" \/>koshirae completa certificada independientemente como <strong data-start=\"3439\" data-end=\"3458\">Tokubetsu Kich\u014d<\/strong>que consta de una saya lacada en kuro-roiro negro y una tsuba redonda de hierro, tal como se indica en la documentaci\u00f3n de la NBTHK.<br data-start=\"3577\" data-end=\"3580\" \/>Blade registrado oficialmente en Jap\u00f3n con una prefectura <strong data-start=\"3636\" data-end=\"3649\">torokusho<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DESCRIPCI\u00d3N DEL ART\u00cdCULO: Incluye kimono o bolsa de algod\u00f3n. Incluye certificado de autenticidad (Supein Nihonto). Incluye copia del certificado de autenticidad (Tokosusho). Incluye certificado NBTHK Tokobetsu kicho para la hoja y el koshirae. Documentaci\u00f3n NBTHK \u2014 HojaClasificaci\u00f3n: Tokubetsu Kich\u014d TokenEstado: Mumei,\u00a0Echizen Bonry\u016bOrganismo emisor: Nihon Bijutsu T\u014dken Hozon Ky\u014dkai NBTHK\u2014 Koshirae Clasificaci\u00f3n: Tokubetsu Kich\u014dObjeto: Koshirae Descripci\u00f3n literal por certificado: Saya: negra Kuro-roiro laca Tsuba: hierro redondo (Maru-gata) Fecha: 20 de febrero de 1967 (Sh\u014dwa 42) Organismo emisor: Nihon Bijutsu T\u014dken Hozon Ky\u014dkai Registro japon\u00e9s \u2014 Torokusho Certificado oficial de registro prefectural japon\u00e9s para una espada antigua.Legal Documento administrativo con n\u00famero de registro y sellos oficiales que confirma el registro legal de la hoja como nihont\u014d. El torokusho no no proporciona informaci\u00f3n sobre el forjador ni la escuela, m\u00e1s all\u00e1 del registro. Escuela Echizen Bonry\u016b Una escuela del per\u00edodo Edo documentada en la provincia de Echizen. La atribuci\u00f3n se expl\u00edcitamente indicada en el certificado NBTHK Tokubetsu Kich\u014d de la hoja. Per\u00edodo Periodo Edo Medio (aprox. siglos XVII-XVIII) Resumen t\u00e9cnico Katana del periodo Edo con una hoja mumei atribuida por la NBTHK a la escuela Echizen Bonry\u016bcertificada como Tokubetsu Kich\u014d Token.koshirae completa certificada independientemente como Tokubetsu Kich\u014dque consta de una saya lacada en kuro-roiro negro y una tsuba redonda de hierro, tal como se indica en la documentaci\u00f3n de la NBTHK.Blade registrado oficialmente en Jap\u00f3n con una prefectura torokusho.<\/p>\n","protected":false},"featured_media":994264,"template":"","meta":[],"product_brand":[],"product_cat":[1079,1078],"product_tag":[1098,1109],"class_list":["post-994247","product","type-product","status-publish","has-post-thumbnail","product_cat-katana-tachi","product_cat-nihonto","product_tag-katana","product_tag-nihonto","first","instock","featured","sold-individually","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Katana nihont\u014d \u00abEchizen Bonry\u016b\u00bb con doble certificado NBTHK - Supein Nihonto<\/title>\n<meta name=\"description\" content=\"Esta hoja se atribuye a Kanemitsu de Seki, seg\u00fan la evaluaci\u00f3n de la NBTHK. El nombre Kanemitsu est\u00e1 asociado a la tradici\u00f3n Mino, en particular a la zona de Seki, uno de los centros de producci\u00f3n de espadas m\u00e1s importantes durante el per\u00edodo Edo. Esta tradici\u00f3n se caracteriza por la geometr\u00eda pr\u00e1ctica de la hoja, un tratamiento t\u00e9rmico fiable y un \u00e9nfasis en la funcionalidad por encima de la decoraci\u00f3n. La atribuci\u00f3n se basa exclusivamente en la evaluaci\u00f3n t\u00e9cnica de la NBTHK.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/supeinnihonto.com\/product\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Katana nihont\u014d \u00abEchizen Bonry\u016b\u00bb con doble certificado NBTHK - Supein Nihonto\" \/>\n<meta property=\"og:description\" content=\"Esta hoja se atribuye a Kanemitsu de Seki, seg\u00fan la evaluaci\u00f3n de la NBTHK. El nombre Kanemitsu est\u00e1 asociado a la tradici\u00f3n Mino, en particular a la zona de Seki, uno de los centros de producci\u00f3n de espadas m\u00e1s importantes durante el per\u00edodo Edo. Esta tradici\u00f3n se caracteriza por la geometr\u00eda pr\u00e1ctica de la hoja, un tratamiento t\u00e9rmico fiable y un \u00e9nfasis en la funcionalidad por encima de la decoraci\u00f3n. La atribuci\u00f3n se basa exclusivamente en la evaluaci\u00f3n t\u00e9cnica de la NBTHK.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/supeinnihonto.com\/product\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\/\" \/>\n<meta property=\"og:site_name\" content=\"Supein Nihonto\" \/>\n<meta property=\"og:image\" content=\"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/7665title-1-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1264\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\\\/\",\"name\":\"Katana nihont\u014d \u00abEchizen Bonry\u016b\u00bb con doble certificado NBTHK - Supein Nihonto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/7665title-1-scaled-1.jpg\",\"datePublished\":\"2026-05-23T10:09:50+00:00\",\"description\":\"Esta hoja se atribuye a Kanemitsu de Seki, seg\u00fan la evaluaci\u00f3n de la NBTHK. El nombre Kanemitsu est\u00e1 asociado a la tradici\u00f3n Mino, en particular a la zona de Seki, uno de los centros de producci\u00f3n de espadas m\u00e1s importantes durante el per\u00edodo Edo. Esta tradici\u00f3n se caracteriza por la geometr\u00eda pr\u00e1ctica de la hoja, un tratamiento t\u00e9rmico fiable y un \u00e9nfasis en la funcionalidad por encima de la decoraci\u00f3n. La atribuci\u00f3n se basa exclusivamente en la evaluaci\u00f3n t\u00e9cnica de la NBTHK.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/7665title-1-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/7665title-1-scaled-1.jpg\",\"width\":2560,\"height\":1264},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/product\\\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Katana nihont\u014d \u00abEchizen Bonry\u016b\u00bb con doble certificado NBTHK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"name\":\"Supein Nihonto\",\"description\":\"Authentic japanese Nihonto katana\",\"publisher\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/supeinnihonto.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\",\"name\":\"SupeinNihonto\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"width\":400,\"height\":400,\"caption\":\"SupeinNihonto\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Katana nihont\u014d \u00abEchizen Bonry\u016b\u00bb con doble certificado NBTHK - Supein Nihonto","description":"Esta hoja se atribuye a Kanemitsu de Seki, seg\u00fan la evaluaci\u00f3n de la NBTHK. El nombre Kanemitsu est\u00e1 asociado a la tradici\u00f3n Mino, en particular a la zona de Seki, uno de los centros de producci\u00f3n de espadas m\u00e1s importantes durante el per\u00edodo Edo. Esta tradici\u00f3n se caracteriza por la geometr\u00eda pr\u00e1ctica de la hoja, un tratamiento t\u00e9rmico fiable y un \u00e9nfasis en la funcionalidad por encima de la decoraci\u00f3n. La atribuci\u00f3n se basa exclusivamente en la evaluaci\u00f3n t\u00e9cnica de la NBTHK.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\/","og_locale":"es_ES","og_type":"article","og_title":"Katana nihont\u014d \u00abEchizen Bonry\u016b\u00bb con doble certificado NBTHK - Supein Nihonto","og_description":"Esta hoja se atribuye a Kanemitsu de Seki, seg\u00fan la evaluaci\u00f3n de la NBTHK. El nombre Kanemitsu est\u00e1 asociado a la tradici\u00f3n Mino, en particular a la zona de Seki, uno de los centros de producci\u00f3n de espadas m\u00e1s importantes durante el per\u00edodo Edo. Esta tradici\u00f3n se caracteriza por la geometr\u00eda pr\u00e1ctica de la hoja, un tratamiento t\u00e9rmico fiable y un \u00e9nfasis en la funcionalidad por encima de la decoraci\u00f3n. La atribuci\u00f3n se basa exclusivamente en la evaluaci\u00f3n t\u00e9cnica de la NBTHK.","og_url":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\/","og_site_name":"Supein Nihonto","og_image":[{"width":2560,"height":1264,"url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/7665title-1-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\/","url":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\/","name":"Katana nihont\u014d \u00abEchizen Bonry\u016b\u00bb con doble certificado NBTHK - Supein Nihonto","isPartOf":{"@id":"https:\/\/supeinnihonto.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\/#primaryimage"},"image":{"@id":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\/#primaryimage"},"thumbnailUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/7665title-1-scaled-1.jpg","datePublished":"2026-05-23T10:09:50+00:00","description":"Esta hoja se atribuye a Kanemitsu de Seki, seg\u00fan la evaluaci\u00f3n de la NBTHK. El nombre Kanemitsu est\u00e1 asociado a la tradici\u00f3n Mino, en particular a la zona de Seki, uno de los centros de producci\u00f3n de espadas m\u00e1s importantes durante el per\u00edodo Edo. Esta tradici\u00f3n se caracteriza por la geometr\u00eda pr\u00e1ctica de la hoja, un tratamiento t\u00e9rmico fiable y un \u00e9nfasis en la funcionalidad por encima de la decoraci\u00f3n. La atribuci\u00f3n se basa exclusivamente en la evaluaci\u00f3n t\u00e9cnica de la NBTHK.","breadcrumb":{"@id":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/supeinnihonto.com\/product\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\/#primaryimage","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/7665title-1-scaled-1.jpg","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/7665title-1-scaled-1.jpg","width":2560,"height":1264},{"@type":"BreadcrumbList","@id":"https:\/\/supeinnihonto.com\/product\/nihonto-katana-echizen-bonryu-with-double-nbthk-certificate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/supeinnihonto.com\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/supeinnihonto.com\/tienda\/"},{"@type":"ListItem","position":3,"name":"Katana nihont\u014d \u00abEchizen Bonry\u016b\u00bb con doble certificado NBTHK"}]},{"@type":"WebSite","@id":"https:\/\/supeinnihonto.com\/#website","url":"https:\/\/supeinnihonto.com\/","name":"Supein Nihonto","description":"Authentic japanese Nihonto katana","publisher":{"@id":"https:\/\/supeinnihonto.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/supeinnihonto.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/supeinnihonto.com\/#organization","name":"SupeinNihonto","url":"https:\/\/supeinnihonto.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","width":400,"height":400,"caption":"SupeinNihonto"},"image":{"@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/994247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/994247\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media\/994264"}],"wp:attachment":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media?parent=994247"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_brand?post=994247"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_cat?post=994247"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_tag?post=994247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}