{"id":994116,"date":"2026-05-23T10:09:53","date_gmt":"2026-05-23T10:09:53","guid":{"rendered":"https:\/\/supeinnihonto.com\/product\/fuchi-kashira-de-shakudo-con-caballos\/"},"modified":"2026-05-23T10:09:53","modified_gmt":"2026-05-23T10:09:53","slug":"fuchi-kashira-de-shakudo-con-caballos","status":"publish","type":"product","link":"https:\/\/supeinnihonto.com\/es\/producto\/fuchi-kashira-de-shakudo-con-caballos\/","title":{"rendered":"Fuchi-kashira de shakud\u014d con caballos"},"content":{"rendered":"<div><em><strong>Art\u00edculo:<\/strong><\/em><\/div>\n<div><\/div>\n<div><span>Caballos Fuchi Kashira de shakudo. Excelente pieza de fuchi kashira, muy bien tallada y llena de detalles. Hecha en shakudo. <\/span><i>Shakudo<\/i><span>Incrustaciones de caballos y mozos de cuadra en un bosque de pinos, firmada\u00a0<i>Soheishi Kitagawa Nyudo Soten sei. Escuela Soten.<br \/>\n <\/i>Muy bien conservada a pesar de los siglos.<br \/>\n<\/span><span>\u00a0Per\u00edodo Edo.\u00a0<\/span><\/div>\n<div><\/div>\n<div>Fuchi: 4 x 2,5 cm<\/div>\n<div>Kashira: 3,8 x 2 cm<\/div>\n<div><\/div>\n<div>Adecuado para katana y wakizashi. <\/div>\n<div><\/div>\n<div class=\"accordion-title active\"><em><strong>\u00bfQu\u00e9 es un fuchi\/kashira?<br \/>\n<\/strong><\/em><br \/>\n<i class=\"fas fa-caret-up\"><\/i><\/div>\n<div class=\"accordion-content active\" id=\"tab3\">\n<p>Un fuchi-kashira es un par de accesorios para espadas que se utilizan en el montaje tradicional japon\u00e9s (koshirae). Se ubican en los extremos de la empu\u00f1adura (tsuka) y cumplen funciones tanto pr\u00e1cticas como decorativas.<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><strong>Fuchi:<\/strong><span>\u00a0<\/span>El fuchi es el collar o funda que se encuentra en la base de la empu\u00f1adura, junto a la guarda (tsuba). Cumple una funci\u00f3n decorativa y protectora, cubriendo la uni\u00f3n entre la empu\u00f1adura y la guarda. El fuchi suele ser de metal y puede presentar diversos dise\u00f1os y motivos, a menudo a juego con el tema de otros accesorios de la espada, como el menuki y la tsuba.<\/li>\n<li><strong>Kashira:<\/strong><span>\u00a0<\/span>La kashira es el pomo o remate de la empu\u00f1adura de la espada, situado en el extremo opuesto a la guarda (tsuba). Su funci\u00f3n es asegurar el enrollado (tsukamaki) de la empu\u00f1adura y contrarrestar el peso de la hoja. Al igual que el fuchi, la kashira suele ser de metal y puede estar adornada con intrincados dise\u00f1os o patrones que complementan la est\u00e9tica general de la espada.\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Juntos, el fuchi y la kashira forman un conjunto armonioso que contribuye al atractivo visual y la funcionalidad de la empu\u00f1adura. Se elaboran con gran atenci\u00f3n al detalle y pueden variar considerablemente en dise\u00f1o, material y mano de obra, reflejando el estilo personal del fabricante de espadas o las preferencias del propietario.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo: Caballos Fuchi Kashira de shakudo. Excelente pieza de fuchi kashira, muy bien tallada y llena de detalles. Hecha en shakudo. ShakudoIncrustaciones de caballos y mozos de cuadra en un bosque de pinos, firmada\u00a0Soheishi Kitagawa Nyudo Soten sei. Escuela Soten. Muy bien conservada a pesar de los siglos. \u00a0Per\u00edodo Edo.\u00a0 Fuchi: 4 x 2,5 cm Kashira: 3,8 x 2 cm Adecuado para katana y wakizashi. \u00bfQu\u00e9 es un fuchi\/kashira? Un fuchi-kashira es un par de accesorios para espadas que se utilizan en el montaje tradicional japon\u00e9s (koshirae). Se ubican en los extremos de la empu\u00f1adura (tsuka) y cumplen funciones tanto pr\u00e1cticas como decorativas. Fuchi:\u00a0El fuchi es el collar o funda que se encuentra en la base de la empu\u00f1adura, junto a la guarda (tsuba). Cumple una funci\u00f3n decorativa y protectora, cubriendo la uni\u00f3n entre la empu\u00f1adura y la guarda. El fuchi suele ser de metal y puede presentar diversos dise\u00f1os y motivos, a menudo a juego con el tema de otros accesorios de la espada, como el menuki y la tsuba. Kashira:\u00a0La kashira es el pomo o remate de la empu\u00f1adura de la espada, situado en el extremo opuesto a la guarda (tsuba). Su funci\u00f3n es asegurar el enrollado (tsukamaki) de la empu\u00f1adura y contrarrestar el peso de la hoja. Al igual que el fuchi, la kashira suele ser de metal y puede estar adornada con intrincados dise\u00f1os o patrones que complementan la est\u00e9tica general de la espada. Juntos, el fuchi y la kashira forman un conjunto armonioso que contribuye al atractivo visual y la funcionalidad de la empu\u00f1adura. Se elaboran con gran atenci\u00f3n al detalle y pueden variar considerablemente en dise\u00f1o, material y mano de obra, reflejando el estilo personal del fabricante de espadas o las preferencias del propietario.<\/p>\n","protected":false},"featured_media":994117,"template":"","meta":[],"product_brand":[],"product_cat":[1084,1083],"product_tag":[],"class_list":["post-994116","product","type-product","status-publish","has-post-thumbnail","product_cat-fuchi-kashira","product_cat-tosogu","first","instock","featured","sold-individually","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fuchi-kashira de shakud\u014d con caballos - Supein Nihonto<\/title>\n<meta name=\"description\" content=\"Caballos Fuchi Kashira de shakudo. Excelente pieza de fuchi kashira, muy bien tallada y llena de detalles. Hecha en shakudo, con incrustaciones de caballos y mozos de cuadra.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/supeinnihonto.com\/es\/producto\/fuchi-kashira-de-shakudo-con-caballos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fuchi-kashira de shakud\u014d con caballos - Supein Nihonto\" \/>\n<meta property=\"og:description\" content=\"Caballos Fuchi Kashira de shakudo. Excelente pieza de fuchi kashira, muy bien tallada y llena de detalles. Hecha en shakudo, con incrustaciones de caballos y mozos de cuadra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/supeinnihonto.com\/es\/producto\/fuchi-kashira-de-shakudo-con-caballos\/\" \/>\n<meta property=\"og:site_name\" content=\"Supein Nihonto\" \/>\n<meta property=\"og:image\" content=\"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/DSC_3892-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/fuchi-kashira-de-shakudo-con-caballos\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/fuchi-kashira-de-shakudo-con-caballos\\\/\",\"name\":\"Fuchi-kashira de shakud\u014d con caballos - Supein Nihonto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/fuchi-kashira-de-shakudo-con-caballos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/fuchi-kashira-de-shakudo-con-caballos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DSC_3892-scaled-1.jpg\",\"datePublished\":\"2026-05-23T10:09:53+00:00\",\"description\":\"Caballos Fuchi Kashira de shakudo. Excelente pieza de fuchi kashira, muy bien tallada y llena de detalles. Hecha en shakudo, con incrustaciones de caballos y mozos de cuadra.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/fuchi-kashira-de-shakudo-con-caballos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/fuchi-kashira-de-shakudo-con-caballos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/fuchi-kashira-de-shakudo-con-caballos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DSC_3892-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/DSC_3892-scaled-1.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Fuchi Kashira shakudo Battle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/es\\\/producto\\\/fuchi-kashira-de-shakudo-con-caballos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/supeinnihonto.com\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fuchi-kashira de shakud\u014d con caballos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#website\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"name\":\"Supein Nihonto\",\"description\":\"Authentic japanese Nihonto katana\",\"publisher\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/supeinnihonto.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#organization\",\"name\":\"SupeinNihonto\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"contentUrl\":\"https:\\\/\\\/supeinnihonto.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/base_logo_transparent_400x400.png\",\"width\":400,\"height\":400,\"caption\":\"SupeinNihonto\"},\"image\":{\"@id\":\"https:\\\/\\\/supeinnihonto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fuchi-kashira de shakud\u014d con caballos - Supein Nihonto","description":"Caballos Fuchi Kashira de shakudo. Excelente pieza de fuchi kashira, muy bien tallada y llena de detalles. Hecha en shakudo, con incrustaciones de caballos y mozos de cuadra.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/supeinnihonto.com\/es\/producto\/fuchi-kashira-de-shakudo-con-caballos\/","og_locale":"es_ES","og_type":"article","og_title":"Fuchi-kashira de shakud\u014d con caballos - Supein Nihonto","og_description":"Caballos Fuchi Kashira de shakudo. Excelente pieza de fuchi kashira, muy bien tallada y llena de detalles. Hecha en shakudo, con incrustaciones de caballos y mozos de cuadra.","og_url":"https:\/\/supeinnihonto.com\/es\/producto\/fuchi-kashira-de-shakudo-con-caballos\/","og_site_name":"Supein Nihonto","og_image":[{"width":2560,"height":1707,"url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/DSC_3892-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/supeinnihonto.com\/es\/producto\/fuchi-kashira-de-shakudo-con-caballos\/","url":"https:\/\/supeinnihonto.com\/es\/producto\/fuchi-kashira-de-shakudo-con-caballos\/","name":"Fuchi-kashira de shakud\u014d con caballos - Supein Nihonto","isPartOf":{"@id":"https:\/\/supeinnihonto.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/supeinnihonto.com\/es\/producto\/fuchi-kashira-de-shakudo-con-caballos\/#primaryimage"},"image":{"@id":"https:\/\/supeinnihonto.com\/es\/producto\/fuchi-kashira-de-shakudo-con-caballos\/#primaryimage"},"thumbnailUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/DSC_3892-scaled-1.jpg","datePublished":"2026-05-23T10:09:53+00:00","description":"Caballos Fuchi Kashira de shakudo. Excelente pieza de fuchi kashira, muy bien tallada y llena de detalles. Hecha en shakudo, con incrustaciones de caballos y mozos de cuadra.","breadcrumb":{"@id":"https:\/\/supeinnihonto.com\/es\/producto\/fuchi-kashira-de-shakudo-con-caballos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/supeinnihonto.com\/es\/producto\/fuchi-kashira-de-shakudo-con-caballos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/es\/producto\/fuchi-kashira-de-shakudo-con-caballos\/#primaryimage","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/DSC_3892-scaled-1.jpg","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2026\/05\/DSC_3892-scaled-1.jpg","width":2560,"height":1707,"caption":"Fuchi Kashira shakudo Battle"},{"@type":"BreadcrumbList","@id":"https:\/\/supeinnihonto.com\/es\/producto\/fuchi-kashira-de-shakudo-con-caballos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/supeinnihonto.com\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/supeinnihonto.com\/tienda\/"},{"@type":"ListItem","position":3,"name":"Fuchi-kashira de shakud\u014d con caballos"}]},{"@type":"WebSite","@id":"https:\/\/supeinnihonto.com\/#website","url":"https:\/\/supeinnihonto.com\/","name":"Supein Nihonto","description":"Authentic japanese Nihonto katana","publisher":{"@id":"https:\/\/supeinnihonto.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/supeinnihonto.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/supeinnihonto.com\/#organization","name":"SupeinNihonto","url":"https:\/\/supeinnihonto.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/","url":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","contentUrl":"https:\/\/supeinnihonto.com\/wp-content\/uploads\/2024\/03\/base_logo_transparent_400x400.png","width":400,"height":400,"caption":"SupeinNihonto"},"image":{"@id":"https:\/\/supeinnihonto.com\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/994116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product\/994116\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media\/994117"}],"wp:attachment":[{"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/media?parent=994116"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_brand?post=994116"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_cat?post=994116"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/supeinnihonto.com\/es\/wp-json\/wp\/v2\/product_tag?post=994116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}